{"id":76764,"date":"2026-03-20T21:41:32","date_gmt":"2026-03-20T17:41:32","guid":{"rendered":"https:\/\/sheniekimi.ge\/ambebi\/?p=76764"},"modified":"2026-03-20T21:41:32","modified_gmt":"2026-03-20T17:41:32","slug":"%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a","status":"publish","type":"post","link":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/","title":{"rendered":"\u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 &#8211; \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1"},"content":{"rendered":"<div class=\"news-text\">\n<p>\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 <a href=\"https:\/\/sheniekimi.ge\/ambebi\/?s=%E1%83%A2%E1%83%A0%E1%83%90%E1%83%9C%E1%83%A1\" target=\"_blank\" rel=\"noopener\">\u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4<\/a> \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, &#8211; \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8.<\/p>\n<p>\u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1.<\/p>\n<p>\u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7:<\/p>\n<p>\u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0);<\/p>\n<p>\u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 &#8211; \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10dc\u10d8\u10d3\u10d0\u10dc \u10e0\u10d4\u10e1\u10de\u10e3\u10d1\u10da\u10d8\u10d9\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10dc\u10d0\u10db\u10d3\u10d4;<\/p>\n<p>\u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8\u10e1 \u10d3\u10d0\u10db\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d4\u10da\u10d8 \u10e7\u10d5\u10d4\u10da\u10d0 \u10e5\u10e3\u10e9\u10d0;<\/p>\n<p>\u10db\u10d4\u10e2\u10d4\u10ee\u10d8\u10e1 \u10ee\u10d8\u10d3\u10d8, \u10d4\u10d5\u10e0\u10dd\u10de\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8;<\/p>\n<p>\u10d1\u10d0\u10e0\u10d0\u10d7\u10d0\u10e8\u10d5\u10d8\u10da\u10d8\u10e1 \u10ee\u10d8\u10d3\u10d8, \u10d1\u10d0\u10e0\u10d0\u10d7\u10d0\u10e8\u10d5\u10d8\u10da\u10d8\u10e1 \u10d0\u10e6\u10db\u10d0\u10e0\u10d7\u10d8;<\/p>\n<p>\u10e5\u10d4\u10d7\u10d4\u10d5\u10d0\u10dc \u10d3\u10d4\u10d3\u10dd\u10e4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 &#8211; \u10e1\u10d0\u10e1\u10e2\u10e3\u10db\u10e0\u10dd \u201e\u10db\u10d4\u10e2\u10d4\u10ee\u10d8\u10d3\u10d0\u10dc\u201c \u10db\u10d4\u10e2\u10e0\u10dd\u10e1\u10d0\u10d3\u10d2\u10e3\u10e0 \u201e\u10d0\u10d5\u10da\u10d0\u10d1\u10e0\u10d8\u10e1\u201c \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7;<\/p>\n<p>\u10d0\u10d5\u10da\u10d8\u10de \u10d6\u10e3\u10e0\u10d0\u10d1\u10d0\u10e8\u10d5\u10d8\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d7\u10d4\u10da\u10d0\u10d5\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d4\u10d1\u10d8, \u10ec\u10e3\u10e0\u10ec\u10e3\u10db\u10d8\u10d0\u10e1 \u10e5\u10e3\u10e9\u10d0, \u10d0\u10ee\u10d5\u10da\u10d4\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8.<br \/>\n\u10d0\u10db \u10de\u10d4\u10e0\u10d8\u10dd\u10d3\u10e8\u10d8 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e8\u10d4\u10e1\u10d0\u10eb\u10da\u10d4\u10d1\u10d4\u10da\u10d8 \u10d8\u10e5\u10dc\u10d4\u10d1\u10d0 \u10d0\u10da\u10e2\u10d4\u10e0\u10dc\u10d0\u10e2\u10d8\u10e3\u10da\u10d8 \u10db\u10d0\u10e0\u10e8\u10e0\u10e3\u10e2\u10d4\u10d1\u10d8\u10d7:<\/p>\n<p>\u10e1\u10dd\u10da\u10dd\u10da\u10d0\u10d9\u10d8\u10d3\u10d0\u10dc \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10dc\u10d0\u10d9\u10d0\u10d3\u10d8 \u10d0\u10e1\u10d0\u10d7\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d8\u10e1 \u10d2\u10d0\u10d5\u10da\u10d8\u10d7 \u10d2\u10dd\u10e0\u10d2\u10d0\u10e1\u10da\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d8\u10e1 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7 \u10d8\u10db\u10dd\u10eb\u10e0\u10d0\u10d5\u10d4\u10d1\u10e1;<br \/>\n\u10d6\u10d4\u10db\u10dd \u10d5\u10d4\u10e0\u10d0\u10d6\u10d4 \u10db\u10dd\u10eb\u10e0\u10d0\u10d5\u10d8 \u10dc\u10d0\u10d9\u10d0\u10d3\u10d8 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10e1 \u10e8\u10d4\u10eb\u10da\u10d4\u10d1\u10e1 \u10d1\u10d0\u10e0\u10dc\u10dd\u10d5\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d8\u10d7, \u10db\u10e0\u10d2\u10d5\u10d0\u10da\u10d8 \u10d1\u10d0\u10e6\u10d8\u10e1 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d1\u10d0\u10e0\u10dc\u10dd\u10d5\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d8\u10d3\u10d0\u10dc \u10db\u10d4\u10da\u10d8\u10e5\u10d8\u10e8\u10d5\u10d8\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8\u10e1 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7 \u10e7\u10d5\u10d4\u10da\u10d0 \u10db\u10d8\u10db\u10d3\u10d4\u10d1\u10d0\u10e0\u10d4 \u10e5\u10e3\u10e9\u10d8\u10e1 \u10d2\u10d0\u10d5\u10da\u10d8\u10d7;<\/p>\n<p>\u10d9\u10dd\u10e2\u10d4 \u10d0\u10e4\u10ee\u10d0\u10d6\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d8\u10d3\u10d0\u10dc \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10d8 \u10d2\u10d0\u10d3\u10d0\u10d8\u10dc\u10d0\u10ea\u10d5\u10da\u10d4\u10d1\u10d4\u10dc \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0\u10d6\u10d4 (\u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d6\u10d4 \u10db\u10dd\u10eb\u10e0\u10d0\u10dd\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10d0\u10e0\u10d8\u10e1 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10e3\u10da\u10d8); \u10da\u10d4\u10e0\u10db\u10dd\u10dc\u10e2\u10dd\u10d5\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10db\u10d0\u10e9\u10d0\u10d1\u10da\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10d5\u10da\u10d8\u10d7 \u10db\u10dd\u10ee\u10d5\u10d3\u10d4\u10d1\u10d8\u10d0\u10dc \u10da\u10d4\u10dd\u10dc\u10d8\u10eb\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0\u10d6\u10d4, \u10e1\u10d0\u10d8\u10d3\u10d0\u10dc\u10d0\u10ea \u10db\u10dd\u10eb\u10e0\u10d0\u10dd\u10d1\u10d0\u10e1 \u10d2\u10d0\u10d0\u10d2\u10e0\u10eb\u10d4\u10da\u10d4\u10d1\u10d4\u10dc \u10e1\u10dd\u10da\u10dd\u10da\u10d0\u10d9\u10d8\u10e1 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7;<\/p>\n<p>\u10e5\u10d4\u10d7\u10d4\u10d5\u10d0\u10dc \u10d3\u10d4\u10d3\u10dd\u10e4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d6\u10d4 \u10db\u10dd\u10eb\u10e0\u10d0\u10d5\u10d8 \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10d8 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10e1 \u10e8\u10d4\u10eb\u10da\u10d4\u10d1\u10d4\u10dc \u10e1\u10d0\u10e1\u10e2\u10e3\u10db\u10e0\u10dd &#8220;\u10e8\u10d4\u10e0\u10d0\u10e2\u10dd\u10dc \u10db\u10d4\u10e2\u10d4\u10ee\u10d8 \u10de\u10d0\u10da\u10d0\u10e1\u10d0\u10db\u10d3\u10d4&#8221;, \u10e1\u10d0\u10d8\u10d3\u10d0\u10dc\u10d0\u10ea \u10d1\u10dd\u10ed\u10dd\u10e0\u10db\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d8\u10e1 \u10d2\u10d0\u10d5\u10da\u10d8\u10d7 \u10db\u10dd\u10eb\u10e0\u10d0\u10dd\u10d1\u10d0\u10e1 \u10d2\u10d0\u10d0\u10d2\u10e0\u10eb\u10d4\u10da\u10d4\u10d1\u10d4\u10dc `\u10e1\u10dd\u10d9\u10d0\u10e0\u10d8\u10e1~ \u10ea\u10d4\u10dc\u10e2\u10e0\u10d0\u10da\u10e3\u10e0\u10d8 \u10dd\u10e4\u10d8\u10e1\u10d8\u10e1 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8.<\/p>\n<p>\u10d0\u10db\u10d0\u10e1\u10d7\u10d0\u10dc, \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u10e0\u10e9\u10d4\u10d1\u10d0, \u10e1\u10d0\u10db\u10d4\u10d1\u10d8\u10e1 \u10e1\u10d0\u10d9\u10d0\u10d7\u10d4\u10d3\u10e0\u10dd \u10e2\u10d0\u10eb\u10e0\u10d8\u10e1 \u10db\u10d8\u10db\u10d3\u10d4\u10d1\u10d0\u10e0\u10d4 \u10e5\u10e3\u10e9\u10d4\u10d1\u10d6\u10d4 \u10e3\u10d9\u10d5\u10d4 \u10d0\u10e0\u10e1\u10d4\u10d1\u10e3\u10da\u10d8 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8.<br \/>\n\u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd \u10d3\u10d0 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d4\u10e0\u10d8\u10d0 \u10db\u10dd\u10e5\u10d0\u10da\u10d0\u10e5\u10d4\u10d4\u10d1\u10e1 \u10db\u10dd\u10e3\u10ec\u10dd\u10d3\u10d4\u10d1\u10e1, \u10d2\u10d0\u10d3\u10d0\u10e3\u10d3\u10d4\u10d1\u10d4\u10da\u10d8 \u10d0\u10e3\u10ea\u10d8\u10da\u10d4\u10d1\u10da\u10dd\u10d1\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0, \u10e1\u10ee\u10d5\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d7\u10d0\u10d5\u10d8 \u10e8\u10d4\u10d8\u10d9\u10d0\u10d5\u10dd\u10dc \u10d0\u10d5\u10e2\u10dd\u10db\u10d0\u10dc\u10e5\u10d0\u10dc\u10d4\u10d1\u10d8\u10d7 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d8\u10e1\u10d2\u10d0\u10dc\u201c, &#8211; \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8.<\/p>\n<\/div>\n<div class=\"social-block\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, &#8211; \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8. \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1. \u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7: \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0); \u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 &#8211; \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":54291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[256],"tags":[8700,6169,8701,8703,8702,8699],"tmauthors":[],"class_list":["post-76764","post","type-post","status-publish","format-standard","has-post-thumbnail","category-256","tag-1500-","tag-6169","tag-8701","tag-8703","tag-8702","tag--21-"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, - \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8. \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1. \u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7: \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0); \u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 - \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"SheniAmbebi.ge\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ka_GE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8 | \u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"SheniAmbebi.ge | \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1\" \/>\n\t\t<meta property=\"og:description\" content=\"\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, - \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8. \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1. \u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7: \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0); \u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 - \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-68f689189504481f140610c3e754d90d.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-68f689189504481f140610c3e754d90d.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t\t<meta property=\"og:image:height\" content=\"755\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-20T17:41:32+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-20T17:41:32+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sheniambebi\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@drpkhakadze\" \/>\n\t\t<meta name=\"twitter:title\" content=\"SheniAmbebi.ge | \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, - \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8. \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1. \u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7: \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0); \u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 - \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@drpkhakadze\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-68f689189504481f140610c3e754d90d.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\\\/#listItem\",\"name\":\"\\u10e1\\u10d0\\u10d6\\u10dd\\u10d2\\u10d0\\u10d3\\u10dd\\u10d4\\u10d1\\u10d0\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\\\/#listItem\",\"position\":2,\"name\":\"\\u10e1\\u10d0\\u10d6\\u10dd\\u10d2\\u10d0\\u10d3\\u10dd\\u10d4\\u10d1\\u10d0\",\"item\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#listItem\",\"name\":\"\\u10e8\\u10e1\\u10e1: 21 \\u10db\\u10d0\\u10e0\\u10e2\\u10e1, 15:00 \\u10e1\\u10d0\\u10d0\\u10d7\\u10d8\\u10d3\\u10d0\\u10dc, \\u10d7\\u10d1\\u10d8\\u10da\\u10d8\\u10e1\\u10d8\\u10e1 \\u10db\\u10d0\\u10e1\\u10e8\\u10e2\\u10d0\\u10d1\\u10d8\\u10d7 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10d8\\u10e1 \\u10d2\\u10d0\\u10d3\\u10d0\\u10d0\\u10d3\\u10d2\\u10d8\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d4\\u10d1\\u10d8 \\u10d3\\u10d0\\u10ec\\u10d4\\u10e1\\u10d3\\u10d4\\u10d1\\u10d0 &#8211; \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d0 \\u10e8\\u10d4\\u10d4\\u10ee\\u10d4\\u10d1\\u10d0, \\u10e0\\u10dd\\u10d2\\u10dd\\u10e0\\u10ea \\u10d9\\u10d4\\u10e0\\u10eb\\u10dd \\u10d0\\u10d5\\u10e2\\u10dd\\u10db\\u10dd\\u10d1\\u10d8\\u10da\\u10d4\\u10d1\\u10e1, \\u10d0\\u10e1\\u10d4\\u10d5\\u10d4, \\u10db\\u10e3\\u10dc\\u10d8\\u10ea\\u10d8\\u10de\\u10d0\\u10da\\u10e3\\u10e0 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10e1\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#listItem\",\"position\":3,\"name\":\"\\u10e8\\u10e1\\u10e1: 21 \\u10db\\u10d0\\u10e0\\u10e2\\u10e1, 15:00 \\u10e1\\u10d0\\u10d0\\u10d7\\u10d8\\u10d3\\u10d0\\u10dc, \\u10d7\\u10d1\\u10d8\\u10da\\u10d8\\u10e1\\u10d8\\u10e1 \\u10db\\u10d0\\u10e1\\u10e8\\u10e2\\u10d0\\u10d1\\u10d8\\u10d7 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10d8\\u10e1 \\u10d2\\u10d0\\u10d3\\u10d0\\u10d0\\u10d3\\u10d2\\u10d8\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d4\\u10d1\\u10d8 \\u10d3\\u10d0\\u10ec\\u10d4\\u10e1\\u10d3\\u10d4\\u10d1\\u10d0 &#8211; \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d0 \\u10e8\\u10d4\\u10d4\\u10ee\\u10d4\\u10d1\\u10d0, \\u10e0\\u10dd\\u10d2\\u10dd\\u10e0\\u10ea \\u10d9\\u10d4\\u10e0\\u10eb\\u10dd \\u10d0\\u10d5\\u10e2\\u10dd\\u10db\\u10dd\\u10d1\\u10d8\\u10da\\u10d4\\u10d1\\u10e1, \\u10d0\\u10e1\\u10d4\\u10d5\\u10d4, \\u10db\\u10e3\\u10dc\\u10d8\\u10ea\\u10d8\\u10de\\u10d0\\u10da\\u10e3\\u10e0 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10e1\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\\\/#listItem\",\"name\":\"\\u10e1\\u10d0\\u10d6\\u10dd\\u10d2\\u10d0\\u10d3\\u10dd\\u10d4\\u10d1\\u10d0\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#newsarticle\",\"name\":\"SheniAmbebi.ge | \\u10e8\\u10e1\\u10e1: 21 \\u10db\\u10d0\\u10e0\\u10e2\\u10e1, 15:00 \\u10e1\\u10d0\\u10d0\\u10d7\\u10d8\\u10d3\\u10d0\\u10dc, \\u10d7\\u10d1\\u10d8\\u10da\\u10d8\\u10e1\\u10d8\\u10e1 \\u10db\\u10d0\\u10e1\\u10e8\\u10e2\\u10d0\\u10d1\\u10d8\\u10d7 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10d8\\u10e1 \\u10d2\\u10d0\\u10d3\\u10d0\\u10d0\\u10d3\\u10d2\\u10d8\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d4\\u10d1\\u10d8 \\u10d3\\u10d0\\u10ec\\u10d4\\u10e1\\u10d3\\u10d4\\u10d1\\u10d0 \\u2013 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d0 \\u10e8\\u10d4\\u10d4\\u10ee\\u10d4\\u10d1\\u10d0, \\u10e0\\u10dd\\u10d2\\u10dd\\u10e0\\u10ea \\u10d9\\u10d4\\u10e0\\u10eb\\u10dd \\u10d0\\u10d5\\u10e2\\u10dd\\u10db\\u10dd\\u10d1\\u10d8\\u10da\\u10d4\\u10d1\\u10e1, \\u10d0\\u10e1\\u10d4\\u10d5\\u10d4, \\u10db\\u10e3\\u10dc\\u10d8\\u10ea\\u10d8\\u10de\\u10d0\\u10da\\u10e3\\u10e0 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10e1\",\"headline\":\"\\u10e8\\u10e1\\u10e1: 21 \\u10db\\u10d0\\u10e0\\u10e2\\u10e1, 15:00 \\u10e1\\u10d0\\u10d0\\u10d7\\u10d8\\u10d3\\u10d0\\u10dc, \\u10d7\\u10d1\\u10d8\\u10da\\u10d8\\u10e1\\u10d8\\u10e1 \\u10db\\u10d0\\u10e1\\u10e8\\u10e2\\u10d0\\u10d1\\u10d8\\u10d7 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10d8\\u10e1 \\u10d2\\u10d0\\u10d3\\u10d0\\u10d0\\u10d3\\u10d2\\u10d8\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d4\\u10d1\\u10d8 \\u10d3\\u10d0\\u10ec\\u10d4\\u10e1\\u10d3\\u10d4\\u10d1\\u10d0 &#8211; \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d0 \\u10e8\\u10d4\\u10d4\\u10ee\\u10d4\\u10d1\\u10d0, \\u10e0\\u10dd\\u10d2\\u10dd\\u10e0\\u10ea \\u10d9\\u10d4\\u10e0\\u10eb\\u10dd \\u10d0\\u10d5\\u10e2\\u10dd\\u10db\\u10dd\\u10d1\\u10d8\\u10da\\u10d4\\u10d1\\u10e1, \\u10d0\\u10e1\\u10d4\\u10d5\\u10d4, \\u10db\\u10e3\\u10dc\\u10d8\\u10ea\\u10d8\\u10de\\u10d0\\u10da\\u10e3\\u10e0 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10e1\",\"author\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/76764-68f689189504481f140610c3e754d90d.jpg\",\"width\":1366,\"height\":755,\"caption\":\"#image_title\"},\"datePublished\":\"2026-03-20T21:41:32+04:00\",\"dateModified\":\"2026-03-20T21:41:32+04:00\",\"inLanguage\":\"ka-GE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#webpage\"},\"articleSection\":\"\\u10e1\\u10d0\\u10d6\\u10dd\\u10d2\\u10d0\\u10d3\\u10dd\\u10d4\\u10d1\\u10d0, 15:00 \\u10e1\\u10d0\\u10d0\\u10d7\\u10d8\\u10d3\\u10d0\\u10dc, \\u10d0\\u10e1\\u10d4\\u10d5\\u10d4, \\u10d7\\u10d1\\u10d8\\u10da\\u10d8\\u10e1\\u10d8\\u10e1 \\u10db\\u10d0\\u10e1\\u10e8\\u10e2\\u10d0\\u10d1\\u10d8\\u10d7 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10d8\\u10e1 \\u10d2\\u10d0\\u10d3\\u10d0\\u10d0\\u10d3\\u10d2\\u10d8\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d4\\u10d1\\u10d8 \\u10d3\\u10d0\\u10ec\\u10d4\\u10e1\\u10d3\\u10d4\\u10d1\\u10d0 - \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d0 \\u10e8\\u10d4\\u10d4\\u10ee\\u10d4\\u10d1\\u10d0, \\u10db\\u10e3\\u10dc\\u10d8\\u10ea\\u10d8\\u10de\\u10d0\\u10da\\u10e3\\u10e0 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10e1, \\u10e0\\u10dd\\u10d2\\u10dd\\u10e0\\u10ea \\u10d9\\u10d4\\u10e0\\u10eb\\u10dd \\u10d0\\u10d5\\u10e2\\u10dd\\u10db\\u10dd\\u10d1\\u10d8\\u10da\\u10d4\\u10d1\\u10e1, \\u10e8\\u10e1\\u10e1: 21 \\u10db\\u10d0\\u10e0\\u10e2\\u10e1\",\"dateline\":\"Published on \\u10db\\u10d0\\u10e0\\u10e2\\u10d8 20, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\",\"name\":\"Sheniambebi\",\"description\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/\",\"telephone\":\"+995577416314\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/76764-8ad006f7e722452ea3f782fb503e5d96.jpg\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#organizationLogo\",\"width\":793,\"height\":228},\"image\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sheniambebi\",\"https:\\\/\\\/x.com\\\/drpkhakadze\",\"https:\\\/\\\/www.instagram.com\\\/sheniambebi.ge\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@shenipulsi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/\",\"name\":\"SheniAmbebi.ge\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#webpage\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/\",\"name\":\"SheniAmbebi.ge | \\u10e8\\u10e1\\u10e1: 21 \\u10db\\u10d0\\u10e0\\u10e2\\u10e1, 15:00 \\u10e1\\u10d0\\u10d0\\u10d7\\u10d8\\u10d3\\u10d0\\u10dc, \\u10d7\\u10d1\\u10d8\\u10da\\u10d8\\u10e1\\u10d8\\u10e1 \\u10db\\u10d0\\u10e1\\u10e8\\u10e2\\u10d0\\u10d1\\u10d8\\u10d7 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10d8\\u10e1 \\u10d2\\u10d0\\u10d3\\u10d0\\u10d0\\u10d3\\u10d2\\u10d8\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d4\\u10d1\\u10d8 \\u10d3\\u10d0\\u10ec\\u10d4\\u10e1\\u10d3\\u10d4\\u10d1\\u10d0 \\u2013 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d0 \\u10e8\\u10d4\\u10d4\\u10ee\\u10d4\\u10d1\\u10d0, \\u10e0\\u10dd\\u10d2\\u10dd\\u10e0\\u10ea \\u10d9\\u10d4\\u10e0\\u10eb\\u10dd \\u10d0\\u10d5\\u10e2\\u10dd\\u10db\\u10dd\\u10d1\\u10d8\\u10da\\u10d4\\u10d1\\u10e1, \\u10d0\\u10e1\\u10d4\\u10d5\\u10d4, \\u10db\\u10e3\\u10dc\\u10d8\\u10ea\\u10d8\\u10de\\u10d0\\u10da\\u10e3\\u10e0 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10e1\",\"description\":\"\\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d9\\u10d0\\u10d7\\u10dd\\u10da\\u10d8\\u10d9\\u10dd\\u10e1-\\u10de\\u10d0\\u10e2\\u10e0\\u10d8\\u10d0\\u10e0\\u10e5\\u10d8\\u10e1, \\u10d8\\u10da\\u10d8\\u10d0 II-\\u10d8\\u10e1 \\u10d2\\u10d0\\u10e0\\u10d3\\u10d0\\u10ea\\u10d5\\u10d0\\u10da\\u10d4\\u10d1\\u10d0\\u10e1\\u10d7\\u10d0\\u10dc \\u10d3\\u10d0\\u10d9\\u10d0\\u10d5\\u10e8\\u10d8\\u10e0\\u10d4\\u10d1\\u10d8\\u10d7, 21 \\u10db\\u10d0\\u10e0\\u10e2\\u10e1 \\u10d7\\u10d1\\u10d8\\u10da\\u10d8\\u10e1\\u10d8\\u10e1 \\u10db\\u10d0\\u10e1\\u10e8\\u10e2\\u10d0\\u10d1\\u10d8\\u10d7 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10d8\\u10e1 \\u10d2\\u10d0\\u10d3\\u10d0\\u10d0\\u10d3\\u10d2\\u10d8\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d4\\u10d1\\u10d8 \\u10d3\\u10d0\\u10ec\\u10d4\\u10e1\\u10d3\\u10d4\\u10d1\\u10d0\\u201c, - \\u10d0\\u10e6\\u10dc\\u10d8\\u10e8\\u10dc\\u10e3\\u10da\\u10d8\\u10d0 \\u10e8\\u10d8\\u10dc\\u10d0\\u10d2\\u10d0\\u10dc \\u10e1\\u10d0\\u10e5\\u10db\\u10d4\\u10d7\\u10d0 \\u10e1\\u10d0\\u10db\\u10d8\\u10dc\\u10d8\\u10e1\\u10e2\\u10e0\\u10dd\\u10e1 \\u10db\\u10d8\\u10d4\\u10e0 \\u10d2\\u10d0\\u10d5\\u10e0\\u10ea\\u10d4\\u10da\\u10d4\\u10d1\\u10e3\\u10da \\u10d2\\u10d0\\u10dc\\u10ea\\u10ee\\u10d0\\u10d3\\u10d4\\u10d1\\u10d0\\u10e8\\u10d8. \\u10d2\\u10d0\\u10dc\\u10ea\\u10ee\\u10d0\\u10d3\\u10d4\\u10d1\\u10d8\\u10e1 \\u10d7\\u10d0\\u10dc\\u10d0\\u10ee\\u10db\\u10d0\\u10d3, \\u10e8\\u10d4\\u10d6\\u10e6\\u10e3\\u10d3\\u10d5\\u10d0 \\u10e8\\u10d4\\u10d4\\u10ee\\u10d4\\u10d1\\u10d0, \\u10e0\\u10dd\\u10d2\\u10dd\\u10e0\\u10ea \\u10d9\\u10d4\\u10e0\\u10eb\\u10dd \\u10d0\\u10d5\\u10e2\\u10dd\\u10db\\u10dd\\u10d1\\u10d8\\u10da\\u10d4\\u10d1\\u10e1, \\u10d0\\u10e1\\u10d4\\u10d5\\u10d4, \\u10db\\u10e3\\u10dc\\u10d8\\u10ea\\u10d8\\u10de\\u10d0\\u10da\\u10e3\\u10e0 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10e1. \\u201e21 \\u10db\\u10d0\\u10e0\\u10e2\\u10e1, 15:00 \\u10e1\\u10d0\\u10d0\\u10d7\\u10d8\\u10d3\\u10d0\\u10dc 00:00 \\u10e1\\u10d0\\u10d0\\u10d7\\u10d0\\u10db\\u10d3\\u10d4 \\u10e2\\u10e0\\u10d0\\u10dc\\u10e1\\u10de\\u10dd\\u10e0\\u10e2\\u10d8\\u10e1 \\u10d2\\u10d0\\u10d3\\u10d0\\u10d0\\u10d3\\u10d2\\u10d8\\u10da\\u10d4\\u10d1\\u10d0 \\u10e1\\u10e0\\u10e3\\u10da\\u10d0\\u10d3 \\u10e8\\u10d4\\u10d8\\u10d6\\u10e6\\u10e3\\u10d3\\u10d4\\u10d1\\u10d0 \\u10e8\\u10d4\\u10db\\u10d3\\u10d4\\u10d2\\u10d8 \\u10db\\u10d8\\u10db\\u10d0\\u10e0\\u10d7\\u10e3\\u10da\\u10d4\\u10d1\\u10d8\\u10d7: \\u10d7\\u10d0\\u10d5\\u10d8\\u10e1\\u10e3\\u10e4\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10db\\u10dd\\u10d4\\u10d3\\u10d0\\u10dc\\u10d8, \\u10e8\\u10d0\\u10da\\u10d5\\u10d0 \\u10d3\\u10d0\\u10d3\\u10d8\\u10d0\\u10dc\\u10d8\\u10e1 \\u10e5\\u10e3\\u10e9\\u10d0 (\\u10d8\\u10ea\\u10d5\\u10da\\u10d4\\u10d1\\u10d0 \\u10db\\u10d8\\u10db\\u10d0\\u10e0\\u10d7\\u10e3\\u10da\\u10d4\\u10d1\\u10d0); \\u10e0\\u10e3\\u10e1\\u10d7\\u10d0\\u10d5\\u10d4\\u10da\\u10d8\\u10e1 \\u10d2\\u10d0\\u10db\\u10d6\\u10d8\\u10e0\\u10d8 - \\u10d7\\u10d0\\u10d5\\u10d8\\u10e1\\u10e3\\u10e4\\u10da\\u10d4\\u10d1\\u10d8\\u10e1\",\"inLanguage\":\"ka-GE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/76764-68f689189504481f140610c3e754d90d.jpg\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#mainImage\",\"width\":1366,\"height\":755,\"caption\":\"#image_title\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\\\/#mainImage\"},\"datePublished\":\"2026-03-20T21:41:32+04:00\",\"dateModified\":\"2026-03-20T21:41:32+04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#website\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/\",\"name\":\"SheniAmbebi\",\"alternateName\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"description\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"inLanguage\":\"ka-GE\",\"publisher\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>SheniAmbebi.ge | \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1<\/title>\n\n","aioseo_head_json":{"title":"SheniAmbebi.ge | \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1","description":"\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, - \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8. \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1. \u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7: \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0); \u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 - \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1","canonical_url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi#listItem","position":1,"name":"Home","item":"https:\/\/sheniekimi.ge\/ambebi","nextItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/#listItem","name":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0"}},{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/#listItem","position":2,"name":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0","item":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#listItem","name":"\u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 &#8211; \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#listItem","position":3,"name":"\u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 &#8211; \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1","previousItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/#listItem","name":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0"}}]},{"@type":"NewsArticle","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#newsarticle","name":"SheniAmbebi.ge | \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1","headline":"\u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 &#8211; \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1","author":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"publisher":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-68f689189504481f140610c3e754d90d.jpg","width":1366,"height":755,"caption":"#image_title"},"datePublished":"2026-03-20T21:41:32+04:00","dateModified":"2026-03-20T21:41:32+04:00","inLanguage":"ka-GE","mainEntityOfPage":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#webpage"},"isPartOf":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#webpage"},"articleSection":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 - \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1","dateline":"Published on \u10db\u10d0\u10e0\u10e2\u10d8 20, 2026."},{"@type":"Organization","@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization","name":"Sheniambebi","description":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","url":"https:\/\/sheniekimi.ge\/ambebi\/","telephone":"+995577416314","logo":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-8ad006f7e722452ea3f782fb503e5d96.jpg","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#organizationLogo","width":793,"height":228},"image":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/sheniambebi","https:\/\/x.com\/drpkhakadze","https:\/\/www.instagram.com\/sheniambebi.ge\/","https:\/\/www.tiktok.com\/@shenipulsi"]},{"@type":"Person","@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author","url":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/","name":"SheniAmbebi.ge"},{"@type":"WebPage","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#webpage","url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/","name":"SheniAmbebi.ge | \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1","description":"\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, - \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8. \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1. \u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7: \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0); \u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 - \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1","inLanguage":"ka-GE","isPartOf":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#website"},"breadcrumb":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#breadcrumblist"},"author":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"creator":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-68f689189504481f140610c3e754d90d.jpg","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#mainImage","width":1366,"height":755,"caption":"#image_title"},"primaryImageOfPage":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/#mainImage"},"datePublished":"2026-03-20T21:41:32+04:00","dateModified":"2026-03-20T21:41:32+04:00"},{"@type":"WebSite","@id":"https:\/\/sheniekimi.ge\/ambebi\/#website","url":"https:\/\/sheniekimi.ge\/ambebi\/","name":"SheniAmbebi","alternateName":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","description":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","inLanguage":"ka-GE","publisher":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization"}}]},"og:locale":"ka_GE","og:site_name":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8 | \u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","og:type":"article","og:title":"SheniAmbebi.ge | \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1","og:description":"\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, - \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8. \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1. \u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7: \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0); \u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 - \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1","og:url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/","og:image":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-68f689189504481f140610c3e754d90d.jpg","og:image:secure_url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-68f689189504481f140610c3e754d90d.jpg","og:image:width":1366,"og:image:height":755,"article:published_time":"2026-03-20T17:41:32+00:00","article:modified_time":"2026-03-20T17:41:32+00:00","article:publisher":"https:\/\/www.facebook.com\/sheniambebi","twitter:card":"summary_large_image","twitter:site":"@drpkhakadze","twitter:title":"SheniAmbebi.ge | \u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1","twitter:description":"\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d9\u10d0\u10d7\u10dd\u10da\u10d8\u10d9\u10dd\u10e1-\u10de\u10d0\u10e2\u10e0\u10d8\u10d0\u10e0\u10e5\u10d8\u10e1, \u10d8\u10da\u10d8\u10d0 II-\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d3\u10d0\u10ea\u10d5\u10d0\u10da\u10d4\u10d1\u10d0\u10e1\u10d7\u10d0\u10dc \u10d3\u10d0\u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d4\u10d1\u10d8\u10d7, 21 \u10db\u10d0\u10e0\u10e2\u10e1 \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0\u201c, - \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8\u10d0 \u10e8\u10d8\u10dc\u10d0\u10d2\u10d0\u10dc \u10e1\u10d0\u10e5\u10db\u10d4\u10d7\u10d0 \u10e1\u10d0\u10db\u10d8\u10dc\u10d8\u10e1\u10e2\u10e0\u10dd\u10e1 \u10db\u10d8\u10d4\u10e0 \u10d2\u10d0\u10d5\u10e0\u10ea\u10d4\u10da\u10d4\u10d1\u10e3\u10da \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d0\u10e8\u10d8. \u10d2\u10d0\u10dc\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10d8\u10e1 \u10d7\u10d0\u10dc\u10d0\u10ee\u10db\u10d0\u10d3, \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1. \u201e21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc 00:00 \u10e1\u10d0\u10d0\u10d7\u10d0\u10db\u10d3\u10d4 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0 \u10e1\u10e0\u10e3\u10da\u10d0\u10d3 \u10e8\u10d4\u10d8\u10d6\u10e6\u10e3\u10d3\u10d4\u10d1\u10d0 \u10e8\u10d4\u10db\u10d3\u10d4\u10d2\u10d8 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7: \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10dd\u10d4\u10d3\u10d0\u10dc\u10d8, \u10e8\u10d0\u10da\u10d5\u10d0 \u10d3\u10d0\u10d3\u10d8\u10d0\u10dc\u10d8\u10e1 \u10e5\u10e3\u10e9\u10d0 (\u10d8\u10ea\u10d5\u10da\u10d4\u10d1\u10d0 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d0); \u10e0\u10e3\u10e1\u10d7\u10d0\u10d5\u10d4\u10da\u10d8\u10e1 \u10d2\u10d0\u10db\u10d6\u10d8\u10e0\u10d8 - \u10d7\u10d0\u10d5\u10d8\u10e1\u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1","twitter:creator":"@drpkhakadze","twitter:image":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/76764-68f689189504481f140610c3e754d90d.jpg"},"aioseo_meta_data":{"post_id":"76764","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-03-20 17:48:54","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-03-20 17:40:11","updated":"2026-03-20 17:51:01","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sheniekimi.ge\/ambebi\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/\" title=\"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0\">\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 \u2013 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/sheniekimi.ge\/ambebi"},{"label":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0","link":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/"},{"label":"\u10e8\u10e1\u10e1: 21 \u10db\u10d0\u10e0\u10e2\u10e1, 15:00 \u10e1\u10d0\u10d0\u10d7\u10d8\u10d3\u10d0\u10dc, \u10d7\u10d1\u10d8\u10da\u10d8\u10e1\u10d8\u10e1 \u10db\u10d0\u10e1\u10e8\u10e2\u10d0\u10d1\u10d8\u10d7 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10d0\u10d3\u10d2\u10d8\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d4\u10d1\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d3\u10d4\u10d1\u10d0 &#8211; \u10e8\u10d4\u10d6\u10e6\u10e3\u10d3\u10d5\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0, \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10d9\u10d4\u10e0\u10eb\u10dd \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d4\u10d1\u10e1, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10db\u10e3\u10dc\u10d8\u10ea\u10d8\u10de\u10d0\u10da\u10e3\u10e0 \u10e2\u10e0\u10d0\u10dc\u10e1\u10de\u10dd\u10e0\u10e2\u10e1","link":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a8%e1%83%a1%e1%83%a1-21-%e1%83%9b%e1%83%90%e1%83%a0%e1%83%a2%e1%83%a1-1500-%e1%83%a1%e1%83%90%e1%83%90%e1%83%97%e1%83%98%e1%83%93%e1%83%90%e1%83%9c-%e1%83%97%e1%83%91%e1%83%98%e1%83%9a\/"}],"_links":{"self":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/76764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/comments?post=76764"}],"version-history":[{"count":1,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/76764\/revisions"}],"predecessor-version":[{"id":76765,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/76764\/revisions\/76765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/media\/54291"}],"wp:attachment":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/media?parent=76764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/categories?post=76764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/tags?post=76764"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/tmauthors?post=76764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}