{"id":73105,"date":"2026-01-23T17:00:44","date_gmt":"2026-01-23T13:00:44","guid":{"rendered":"https:\/\/sheniekimi.ge\/ambebi\/?p=73105"},"modified":"2026-01-23T17:00:44","modified_gmt":"2026-01-23T13:00:44","slug":"%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0","status":"publish","type":"post","link":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/","title":{"rendered":"\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 &#8211; \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8"},"content":{"rendered":"<div class=\"news-text\">\n<p>17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8<a href=\"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a9%e1%83%94%e1%83%9b%e1%83%98-%e1%83%93%e1%83%90-%e1%83%98%e1%83%9a%e1%83%98%e1%83%99%e1%83%9d%e1%83%a1-%e1%83%a0%e1%83%94%e1%83%9e%e1%83%94%e1%83%a2%e1%83%98%e1%83%aa%e1%83%98%e1%83%98\/\" target=\"_blank\" rel=\"noopener\"> \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8<\/a> \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1.<\/p>\n<p>\u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8\u00a0<a href=\"https:\/\/www.facebook.com\/share\/1AYcofzVhm\/?mibextid=wwXIfr\" target=\"_blank\" rel=\"noopener\">\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0,<\/a>\u00a0\u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8\u00a0<a href=\"https:\/\/www.facebook.com\/share\/18DFURGcy4\/?mibextid=wwXIfr\" target=\"_blank\" rel=\"noopener\">Emolas Corporation<\/a>\u00a0\u10d8\u10e7\u10dd.<\/p>\n<p>1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8, \u10d4\u10da\u10d0 \u10e4\u10d8\u10ea\u10ef\u10d4\u10e0\u10d0\u10da\u10d3\u10d8, \u10db\u10d0\u10d8\u10da\u10e1 \u10d3\u10d4\u10d5\u10d8\u10e1\u10d8, \u10d0\u10e0\u10d4\u10e2\u10d0 \u10e4\u10e0\u10d0\u10dc\u10d9\u10da\u10d8\u10dc\u10d8, \u10db\u10d0\u10e0\u10d8\u10d0 \u10d9\u10d0\u10da\u10d0\u10e1\u10d8, The Beatles \u10d3\u10d0 \u10e1\u10ee\u10d5\u10d0 \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10d8, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d8\u10d4\u10e1. \u00a0\u10db\u10d0\u10d7\u10d8 \u10d7\u10d8\u10d7\u10dd\u10d4\u10e3\u10da\u10d8 \u10d9\u10dd\u10dc\u10ea\u10d4\u10e0\u10e2\u10d8 \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10e3\u10da \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0\u10d3 \u10d8\u10e5\u10ea\u10d0, \u10e0\u10dd\u10db\u10d4\u10da\u10db\u10d0\u10ea \u10d7\u10d0\u10dd\u10d1\u10d4\u10d1\u10d8 \u10d2\u10d0\u10d0\u10d4\u10e0\u10d7\u10d8\u10d0\u10dc\u10d0 \u10d3\u10d0 \u10d3\u10e0\u10dd\u10e1 <a href=\"https:\/\/sheniekimi.ge\/ambebi\/\" target=\"_blank\" rel=\"noopener\">\u10d2\u10d0\u10e3\u10eb\u10da\u10dd.<\/a><\/p>\n<p>\u10db\u10d0\u10d7 \u10e0\u10d8\u10d2\u10e1 \u10e3\u10d9\u10d5\u10d4 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d0\u10ea \u10e8\u10d4\u10e3\u10d4\u10e0\u10d7\u10d3\u10d0. \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10d9\u10dd\u10dc\u10ea\u10d4\u10e0\u10e2\u10db\u10d0 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10e8\u10d8 \u10d3\u10d0\u10d0\u10d3\u10d0\u10e1\u10e2\u10e3\u10e0\u10d0, \u10e0\u10dd\u10db \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10d4\u10e0\u10dd\u10d5\u10dc\u10e3\u10da\u10d8 \u10ea\u10d4\u10d9\u10d5\u10d0 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d8\u10d0.<\/p>\n<p>\u10d0\u10e6\u10e1\u10d0\u10dc\u10d8\u10e8\u10dc\u10d0\u10d5\u10d8\u10d0, \u10e0\u10dd\u10db \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8 \u10d0\u10e5\u10e2\u10d8\u10e3\u10e0 \u10e0\u10d4\u10df\u10d8\u10db\u10e8\u10d8 \u10e3\u10ed\u10d4\u10e0\u10e1 \u10db\u10ee\u10d0\u10e0\u10e1 \u10e1\u10d0\u10d6\u10e6\u10d5\u10d0\u10e0\u10d2\u10d0\u10e0\u10d4\u10d7 \u10db\u10ea\u10ee\u10dd\u10d5\u10e0\u10d4\u10d1 \u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10d4\u10d1\u10e1 \u10d3\u10d0 \u10db\u10d0\u10d7\u10d7\u10d5\u10d8\u10e1 \u10d0\u10e0\u10d0\u10d4\u10e0\u10d7 \u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10e1 \u10d0\u10ee\u10dd\u10e0\u10ea\u10d8\u10d4\u10da\u10d4\u10d1\u10e1 \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10e1\u10d0\u10d1\u10d0\u10dc\u10d9\u10dd \u10e1\u10d4\u10e0\u10d5\u10d8\u10e1\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10dc\u10d5\u10d8\u10d7\u10d0\u10e0\u10d4\u10d1\u10d8\u10e1, \u00a0\u10d8\u10e1\u10d4 \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10e3\u10da\u10d8 \u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10dc\u10ee\u10dd\u10e0\u10ea\u10d8\u10d4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10db\u10d0\u10e0\u10d7\u10e3\u10da\u10d4\u10d1\u10d8\u10d7. \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10d9\u10dd\u10dc\u10ea\u10d4\u10e0\u10e2\u10d8\u10e1 \u10db\u10ee\u10d0\u10e0\u10d3\u10d0\u10ed\u10d4\u10e0\u10d0 \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10db \u10ee\u10d4\u10d3\u10d5\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d8\u10d0.<\/p>\n<p>\u201e\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10d2\u10d0\u10db\u10dd\u10e1\u10d5\u10da\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0\u10d0, \u10e0\u10dd\u10db\u10d4\u10da\u10d8\u10ea \u10d2\u10d0\u10dc\u10e1\u10d0\u10d9\u10e3\u10d7\u10e0\u10d4\u10d1\u10e3\u10da\u10d0\u10d3 \u10db\u10dc\u10d8\u10e8\u10d5\u10dc\u10d4\u10da\u10dd\u10d5\u10d0\u10dc\u10d8\u10d0 \u10e1\u10d0\u10d6\u10e6\u10d5\u10d0\u10e0\u10d2\u10d0\u10e0\u10d4\u10d7 \u10db\u10ea\u10ee\u10dd\u10d5\u10e0\u10d4\u10d1\u10d8 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10d7\u10d0\u10dc\u10d0\u10db\u10d4\u10db\u10d0\u10db\u10e3\u10da\u10d4\u10d4\u10d1\u10d8\u10e1\u10d7\u10d5\u10d8\u10e1. \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8 \u10e3\u10d9\u10d5\u10d4 \u10ec\u10da\u10d4\u10d1\u10d8\u10d0 \u10d0\u10e5\u10e2\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d0\u10ee\u10dd\u10e0\u10ea\u10d8\u10d4\u10da\u10d4\u10d1\u10e1 \u10d4\u10db\u10d8\u10d2\u10e0\u10d0\u10dc\u10e2\u10d4\u10d1\u10d6\u10d4 \u10dd\u10e0\u10d8\u10d4\u10dc\u10e2\u10d8\u10e0\u10d4\u10d1\u10e3\u10da \u10d0\u10e0\u10d0\u10d4\u10e0\u10d7 \u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10e1 \u10e0\u10dd\u10d2\u10dd\u10e0\u10ea \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10e1\u10d4\u10e0\u10d5\u10d8\u10e1\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10dc\u10d5\u10d8\u10d7\u10d0\u10e0\u10d4\u10d1\u10d8\u10e1, \u10d8\u10e1\u10d4 \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10e3\u10da\u10d8 \u10d3\u10d0 \u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10e0\u10d8\u10d5\u10d8 \u10d8\u10dc\u10d8\u10ea\u10d8\u10d0\u10e2\u10d8\u10d5\u10d4\u10d1\u10d8\u10e1 \u10db\u10ee\u10d0\u10e0\u10d3\u10d0\u10ed\u10d4\u10e0\u10d8\u10e1 \u10d9\u10e3\u10d7\u10ee\u10d8\u10d7. \u10e9\u10d5\u10d4\u10dc\u10d7\u10d5\u10d8\u10e1 \u10d2\u10d0\u10dc\u10e1\u10d0\u10d9\u10e3\u10d7\u10e0\u10d4\u10d1\u10d8\u10d7 \u10e1\u10d0\u10d0\u10db\u10d0\u10e7\u10dd\u10d0, \u10e0\u10dd\u10db \u10d0\u10db \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dc\u10d8\u10e8\u10d5\u10dc\u10d4\u10da\u10dd\u10d1\u10d8\u10e1 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d8\u10e1 \u10db\u10ee\u10d0\u10e0\u10d3\u10d0\u10db\u10ed\u10d4\u10e0\u10d4\u10d1\u10d8 \u10d5\u10d0\u10e0\u10d7. \u10db\u10e1\u10d2\u10d0\u10d5\u10e1\u10d8 \u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d4\u10d1\u10d8 \u10d2\u10d5\u10d0\u10eb\u10da\u10d4\u10d5\u10e1 \u10e8\u10d4\u10e1\u10d0\u10eb\u10da\u10d4\u10d1\u10da\u10dd\u10d1\u10d0\u10e1 \u10d4\u10db\u10d8\u10d2\u10e0\u10d0\u10dc\u10e2\u10d4\u10d1\u10d8\u10e1\u10d7\u10d5\u10d8\u10e1 \u10e8\u10d4\u10d5\u10e5\u10db\u10dc\u10d0\u10d7 \u10d9\u10d0\u10d5\u10e8\u10d8\u10e0\u10d8 \u10e1\u10d0\u10d9\u10e3\u10d7\u10d0\u10e0 \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d0\u10e1\u10d7\u10d0\u10dc, \u10e1\u10d0\u10d3\u10d0\u10ea \u10d0\u10e0 \u10e3\u10dc\u10d3\u10d0 \u10d8\u10e7\u10d5\u10dc\u10d4\u10dc \u10d8\u10e1\u10d8\u10dc\u10d8\u201d, &#8211; \u10d2\u10d0\u10dc\u10d0\u10ea\u10ee\u10d0\u10d3\u10d0 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10e1 \u10d4\u10db\u10d8\u10d2\u10e0\u10d0\u10dc\u10e2\u10d4\u10d1\u10d8\u10e1 \u10e1\u10d0\u10d1\u10d0\u10dc\u10d9\u10dd \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10d3\u10d8\u10e0\u10d4\u10e5\u10e2\u10dd\u10e0\u10db\u10d0, \u10dc\u10d0\u10e2\u10d0\u10da\u10d8\u10d0 \u10e8\u10d0\u10d7\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0.<\/p>\n<p>\u10d7\u10e3 \u10e5\u10d5\u10d4\u10e7\u10dc\u10d8\u10e1 \u10e1\u10d0\u10d6\u10e6\u10d5\u10e0\u10d4\u10d1\u10e1 \u10d2\u10d0\u10e0\u10d4\u10d7 \u10ea\u10ee\u10dd\u10d5\u10e0\u10dd\u10d1\u10d7 \u10d3\u10d0 \u10d2\u10d8\u10e7\u10d5\u10d0\u10e0\u10d7 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d0, \u10e8\u10d4\u10db\u10dd\u10e3\u10d4\u10e0\u10d7\u10d3\u10d8\u10d7\u00a0<a href=\"https:\/\/bankofgeorgia.ge\/blog\/siakhleebi\/ratom-unda-sheuertde-emigrantebis-peisbuk-jgups\/\" target=\"_blank\" rel=\"noopener\">\u10d4\u10db\u10d8\u10d2\u10e0\u10d0\u10dc\u10e2\u10d4\u10d1\u10d8\u10e1 \u10ef\u10d2\u10e3\u10e4\u10e1,<\/a>\u00a0\u10e0\u10dd\u10db \u10db\u10e1\u10d2\u10d0\u10d5\u10e1\u10d8 \u10d3\u10e6\u10d4\u10d4\u10d1\u10d8 \u10d4\u10e0\u10d7\u10d0\u10d3 \u10d0\u10e6\u10d5\u10dc\u10d8\u10e8\u10dc\u10dd\u10d7!<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1. \u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8\u00a0\u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0,\u00a0\u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8\u00a0Emolas Corporation\u00a0\u10d8\u10e7\u10dd. 1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":73106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[256],"tags":[7143],"tmauthors":[],"class_list":["post-73105","post","type-post","status-publish","format-standard","has-post-thumbnail","category-256","tag-7143"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1. \u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0, \u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8 Emolas Corporation \u10d8\u10e7\u10dd. 1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"SheniAmbebi.ge\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ka_GE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8 | \u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"SheniAmbebi.ge | \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8\" \/>\n\t\t<meta property=\"og:description\" content=\"17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1. \u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0, \u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8 Emolas Corporation \u10d8\u10e7\u10dd. 1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8,\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-c0f613401c85288102d2d009f2f94f6e.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-c0f613401c85288102d2d009f2f94f6e.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1063\" \/>\n\t\t<meta property=\"og:image:height\" content=\"579\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-23T13:00:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-23T13:00:44+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sheniambebi\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@drpkhakadze\" \/>\n\t\t<meta name=\"twitter:title\" content=\"SheniAmbebi.ge | \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8\" \/>\n\t\t<meta name=\"twitter:description\" content=\"17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1. \u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0, \u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8 Emolas Corporation \u10d8\u10e7\u10dd. 1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8,\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@drpkhakadze\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-c0f613401c85288102d2d009f2f94f6e.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\\\/#listItem\",\"name\":\"\\u10e1\\u10d0\\u10d6\\u10dd\\u10d2\\u10d0\\u10d3\\u10dd\\u10d4\\u10d1\\u10d0\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\\\/#listItem\",\"position\":2,\"name\":\"\\u10e1\\u10d0\\u10d6\\u10dd\\u10d2\\u10d0\\u10d3\\u10dd\\u10d4\\u10d1\\u10d0\",\"item\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#listItem\",\"name\":\"\\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e2\\u10e0\\u10d8\\u10e3\\u10db\\u10e4\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 | \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 &#8211; \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d8\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#listItem\",\"position\":3,\"name\":\"\\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e2\\u10e0\\u10d8\\u10e3\\u10db\\u10e4\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 | \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 &#8211; \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d8\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\\\/#listItem\",\"name\":\"\\u10e1\\u10d0\\u10d6\\u10dd\\u10d2\\u10d0\\u10d3\\u10dd\\u10d4\\u10d1\\u10d0\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#newsarticle\",\"name\":\"SheniAmbebi.ge | \\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e2\\u10e0\\u10d8\\u10e3\\u10db\\u10e4\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 | \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 \\u2013 \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d8\",\"headline\":\"\\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e2\\u10e0\\u10d8\\u10e3\\u10db\\u10e4\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 | \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 &#8211; \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d8\",\"author\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/73105-c0f613401c85288102d2d009f2f94f6e.jpg\",\"width\":1063,\"height\":579,\"caption\":\"\\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e2\\u10e0\\u10d8\\u10e3\\u10db\\u10e4\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 | \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 - \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d8\"},\"datePublished\":\"2026-01-23T17:00:44+04:00\",\"dateModified\":\"2026-01-23T17:00:44+04:00\",\"inLanguage\":\"ka-GE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#webpage\"},\"articleSection\":\"\\u10e1\\u10d0\\u10d6\\u10dd\\u10d2\\u10d0\\u10d3\\u10dd\\u10d4\\u10d1\\u10d0, \\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e2\\u10e0\\u10d8\\u10e3\\u10db\\u10e4\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 | \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 - \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d8\",\"dateline\":\"Published on \\u10d8\\u10d0\\u10dc\\u10d5\\u10d0\\u10e0\\u10d8 23, 2026.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\",\"name\":\"Sheniambebi\",\"description\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/\",\"telephone\":\"+995577416314\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/73105-8ad006f7e722452ea3f782fb503e5d96.jpg\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#organizationLogo\",\"width\":793,\"height\":228},\"image\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sheniambebi\",\"https:\\\/\\\/x.com\\\/drpkhakadze\",\"https:\\\/\\\/www.instagram.com\\\/sheniambebi.ge\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@shenipulsi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/\",\"name\":\"SheniAmbebi.ge\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#webpage\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/\",\"name\":\"SheniAmbebi.ge | \\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e2\\u10e0\\u10d8\\u10e3\\u10db\\u10e4\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 | \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 \\u2013 \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d8\",\"description\":\"17 \\u10d8\\u10d0\\u10dc\\u10d5\\u10d0\\u10e0\\u10e1 \\u10e5\\u10d0\\u10e0\\u10d7\\u10e3\\u10da\\u10d8 \\u10dc\\u10d0\\u10ea\\u10d8\\u10dd\\u10dc\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d1\\u10d0\\u10da\\u10d4\\u10e2\\u10d8 \\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10da\\u10d4\\u10d2\\u10d4\\u10dc\\u10d3\\u10d0\\u10e0\\u10e3\\u10da \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 \\u10ec\\u10d0\\u10e0\\u10e1\\u10d3\\u10d2\\u10d0. \\u10d4\\u10e1 \\u10d8\\u10e1\\u10e2\\u10dd\\u10e0\\u10d8\\u10e3\\u10da\\u10d8 \\u10db\\u10dd\\u10d5\\u10da\\u10d4\\u10dc\\u10d0 \\u10e5\\u10d0\\u10e0\\u10d7\\u10e3\\u10da \\u10ee\\u10d4\\u10da\\u10dd\\u10d5\\u10dc\\u10d4\\u10d1\\u10d0\\u10e1 \\u10db\\u10e1\\u10dd\\u10e4\\u10da\\u10d8\\u10dd \\u10d9\\u10e3\\u10da\\u10e2\\u10e3\\u10e0\\u10d8\\u10e1\\u10d0 \\u10d3\\u10d0 \\u10d8\\u10e1\\u10e2\\u10dd\\u10e0\\u10d8\\u10d8\\u10e1 \\u10dc\\u10d0\\u10ec\\u10d8\\u10da\\u10d0\\u10d3 \\u10d0\\u10e5\\u10ea\\u10d4\\u10d5\\u10e1. \\u10db\\u10e3\\u10d3\\u10db\\u10d8\\u10d5\\u10d8 \\u10ec\\u10d8\\u10dc\\u10e1\\u10d5\\u10da\\u10d8\\u10e1\\u10d0 \\u10d3\\u10d0 \\u10d0\\u10e0\\u10d2\\u10d0\\u10e9\\u10d4\\u10e0\\u10d4\\u10d1\\u10d8\\u10e1 \\u10de\\u10e0\\u10dd\\u10ea\\u10d4\\u10e1\\u10e8\\u10d8 \\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d9\\u10d8\\u10d0, \\u10e6\\u10dd\\u10dc\\u10d8\\u10e1\\u10eb\\u10d8\\u10d4\\u10d1\\u10d8\\u10e1 \\u10dd\\u10e0\\u10d2\\u10d0\\u10dc\\u10d8\\u10d6\\u10d0\\u10e2\\u10dd\\u10e0\\u10d8 \\u10d9\\u10d8 Emolas Corporation \\u10d8\\u10e7\\u10dd. 1891 \\u10ec\\u10d4\\u10da\\u10e1 \\u10d2\\u10d0\\u10ee\\u10e1\\u10dc\\u10d8\\u10da\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8 \\u10e1\\u10d0\\u10e3\\u10d9\\u10e3\\u10dc\\u10d4\\u10d6\\u10d4 \\u10db\\u10d4\\u10e2\\u10d8\\u10d0 \\u10d2\\u10d0\\u10db\\u10dd\\u10e0\\u10e9\\u10d4\\u10e3\\u10da \\u10d0\\u10e0\\u10e2\\u10d8\\u10e1\\u10e2\\u10d4\\u10d1\\u10e1 \\u10db\\u10d0\\u10e1\\u10de\\u10d8\\u10dc\\u10eb\\u10da\\u10dd\\u10d1\\u10e1. \\u10db\\u10d0\\u10d7, \\u10e0\\u10dd\\u10db\\u10da\\u10d4\\u10d1\\u10db\\u10d0\\u10ea \\u10d4\\u10de\\u10dd\\u10e5\\u10d4\\u10d1\\u10d8 \\u10e8\\u10d4\\u10e5\\u10db\\u10dc\\u10d4\\u10e1. \\u10e1\\u10ec\\u10dd\\u10e0\\u10d4\\u10d3 \\u10d0\\u10e5 \\u10d8\\u10d3\\u10d2\\u10dc\\u10d4\\u10dc \\u10d1\\u10d8\\u10da\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10d3\\u10d4\\u10d8, \\u10da\\u10e3\\u10d8 \\u10d0\\u10e0\\u10db\\u10e1\\u10e2\\u10e0\\u10dd\\u10dc\\u10d2\\u10d8,\",\"inLanguage\":\"ka-GE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/73105-c0f613401c85288102d2d009f2f94f6e.jpg\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#mainImage\",\"width\":1063,\"height\":579,\"caption\":\"\\u10e1\\u10e3\\u10ee\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e2\\u10e0\\u10d8\\u10e3\\u10db\\u10e4\\u10d8 \\u10d9\\u10d0\\u10e0\\u10dc\\u10d4\\u10d2\\u10d8 \\u10f0\\u10dd\\u10da\\u10d8\\u10e1 \\u10e1\\u10ea\\u10d4\\u10dc\\u10d0\\u10d6\\u10d4 | \\u10db\\u10d7\\u10d0\\u10d5\\u10d0\\u10e0\\u10d8 \\u10e1\\u10de\\u10dd\\u10dc\\u10e1\\u10dd\\u10e0\\u10d8 - \\u10e1\\u10d0\\u10e5\\u10d0\\u10e0\\u10d7\\u10d5\\u10d4\\u10da\\u10dd\\u10e1 \\u10d1\\u10d0\\u10dc\\u10d8\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\\\/#mainImage\"},\"datePublished\":\"2026-01-23T17:00:44+04:00\",\"dateModified\":\"2026-01-23T17:00:44+04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#website\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/\",\"name\":\"SheniAmbebi\",\"alternateName\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"description\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"inLanguage\":\"ka-GE\",\"publisher\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>SheniAmbebi.ge | \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8<\/title>\n\n","aioseo_head_json":{"title":"SheniAmbebi.ge | \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","description":"17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1. \u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0, \u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8 Emolas Corporation \u10d8\u10e7\u10dd. 1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8,","canonical_url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi#listItem","position":1,"name":"Home","item":"https:\/\/sheniekimi.ge\/ambebi","nextItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/#listItem","name":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0"}},{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/#listItem","position":2,"name":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0","item":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#listItem","name":"\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 &#8211; \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#listItem","position":3,"name":"\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 &#8211; \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","previousItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/#listItem","name":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0"}}]},{"@type":"NewsArticle","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#newsarticle","name":"SheniAmbebi.ge | \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","headline":"\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 &#8211; \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","author":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"publisher":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-c0f613401c85288102d2d009f2f94f6e.jpg","width":1063,"height":579,"caption":"\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 - \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8"},"datePublished":"2026-01-23T17:00:44+04:00","dateModified":"2026-01-23T17:00:44+04:00","inLanguage":"ka-GE","mainEntityOfPage":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#webpage"},"isPartOf":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#webpage"},"articleSection":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0, \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 - \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","dateline":"Published on \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10d8 23, 2026."},{"@type":"Organization","@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization","name":"Sheniambebi","description":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","url":"https:\/\/sheniekimi.ge\/ambebi\/","telephone":"+995577416314","logo":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-8ad006f7e722452ea3f782fb503e5d96.jpg","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#organizationLogo","width":793,"height":228},"image":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/sheniambebi","https:\/\/x.com\/drpkhakadze","https:\/\/www.instagram.com\/sheniambebi.ge\/","https:\/\/www.tiktok.com\/@shenipulsi"]},{"@type":"Person","@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author","url":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/","name":"SheniAmbebi.ge"},{"@type":"WebPage","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#webpage","url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/","name":"SheniAmbebi.ge | \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","description":"17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1. \u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0, \u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8 Emolas Corporation \u10d8\u10e7\u10dd. 1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8,","inLanguage":"ka-GE","isPartOf":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#website"},"breadcrumb":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#breadcrumblist"},"author":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"creator":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-c0f613401c85288102d2d009f2f94f6e.jpg","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#mainImage","width":1063,"height":579,"caption":"\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 - \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8"},"primaryImageOfPage":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/#mainImage"},"datePublished":"2026-01-23T17:00:44+04:00","dateModified":"2026-01-23T17:00:44+04:00"},{"@type":"WebSite","@id":"https:\/\/sheniekimi.ge\/ambebi\/#website","url":"https:\/\/sheniekimi.ge\/ambebi\/","name":"SheniAmbebi","alternateName":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","description":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","inLanguage":"ka-GE","publisher":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization"}}]},"og:locale":"ka_GE","og:site_name":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8 | \u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","og:type":"article","og:title":"SheniAmbebi.ge | \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","og:description":"17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1. \u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0, \u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8 Emolas Corporation \u10d8\u10e7\u10dd. 1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8,","og:url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/","og:image":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-c0f613401c85288102d2d009f2f94f6e.jpg","og:image:secure_url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-c0f613401c85288102d2d009f2f94f6e.jpg","og:image:width":1063,"og:image:height":579,"article:published_time":"2026-01-23T13:00:44+00:00","article:modified_time":"2026-01-23T13:00:44+00:00","article:publisher":"https:\/\/www.facebook.com\/sheniambebi","twitter:card":"summary_large_image","twitter:site":"@drpkhakadze","twitter:title":"SheniAmbebi.ge | \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","twitter:description":"17 \u10d8\u10d0\u10dc\u10d5\u10d0\u10e0\u10e1 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da\u10d8 \u10dc\u10d0\u10ea\u10d8\u10dd\u10dc\u10d0\u10da\u10e3\u10e0\u10d8 \u10d1\u10d0\u10da\u10d4\u10e2\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10da\u10d4\u10d2\u10d4\u10dc\u10d3\u10d0\u10e0\u10e3\u10da \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 \u10ec\u10d0\u10e0\u10e1\u10d3\u10d2\u10d0. \u10d4\u10e1 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10e3\u10da\u10d8 \u10db\u10dd\u10d5\u10da\u10d4\u10dc\u10d0 \u10e5\u10d0\u10e0\u10d7\u10e3\u10da \u10ee\u10d4\u10da\u10dd\u10d5\u10dc\u10d4\u10d1\u10d0\u10e1 \u10db\u10e1\u10dd\u10e4\u10da\u10d8\u10dd \u10d9\u10e3\u10da\u10e2\u10e3\u10e0\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d8\u10e1\u10e2\u10dd\u10e0\u10d8\u10d8\u10e1 \u10dc\u10d0\u10ec\u10d8\u10da\u10d0\u10d3 \u10d0\u10e5\u10ea\u10d4\u10d5\u10e1. \u10db\u10e3\u10d3\u10db\u10d8\u10d5\u10d8 \u10ec\u10d8\u10dc\u10e1\u10d5\u10da\u10d8\u10e1\u10d0 \u10d3\u10d0 \u10d0\u10e0\u10d2\u10d0\u10e9\u10d4\u10e0\u10d4\u10d1\u10d8\u10e1 \u10de\u10e0\u10dd\u10ea\u10d4\u10e1\u10e8\u10d8 \u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d9\u10d8\u10d0, \u10e6\u10dd\u10dc\u10d8\u10e1\u10eb\u10d8\u10d4\u10d1\u10d8\u10e1 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10e2\u10dd\u10e0\u10d8 \u10d9\u10d8 Emolas Corporation \u10d8\u10e7\u10dd. 1891 \u10ec\u10d4\u10da\u10e1 \u10d2\u10d0\u10ee\u10e1\u10dc\u10d8\u10da\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8 \u10e1\u10d0\u10e3\u10d9\u10e3\u10dc\u10d4\u10d6\u10d4 \u10db\u10d4\u10e2\u10d8\u10d0 \u10d2\u10d0\u10db\u10dd\u10e0\u10e9\u10d4\u10e3\u10da \u10d0\u10e0\u10e2\u10d8\u10e1\u10e2\u10d4\u10d1\u10e1 \u10db\u10d0\u10e1\u10de\u10d8\u10dc\u10eb\u10da\u10dd\u10d1\u10e1. \u10db\u10d0\u10d7, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10db\u10d0\u10ea \u10d4\u10de\u10dd\u10e5\u10d4\u10d1\u10d8 \u10e8\u10d4\u10e5\u10db\u10dc\u10d4\u10e1. \u10e1\u10ec\u10dd\u10e0\u10d4\u10d3 \u10d0\u10e5 \u10d8\u10d3\u10d2\u10dc\u10d4\u10dc \u10d1\u10d8\u10da\u10d8 \u10f0\u10dd\u10da\u10d8\u10d3\u10d4\u10d8, \u10da\u10e3\u10d8 \u10d0\u10e0\u10db\u10e1\u10e2\u10e0\u10dd\u10dc\u10d2\u10d8,","twitter:creator":"@drpkhakadze","twitter:image":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/73105-c0f613401c85288102d2d009f2f94f6e.jpg"},"aioseo_meta_data":{"post_id":"73105","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-07-22 20:09:25","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-01-23 12:58:35","updated":"2026-07-22 20:09:25","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sheniekimi.ge\/ambebi\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/\" title=\"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0\">\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 \u2013 \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/sheniekimi.ge\/ambebi"},{"label":"\u10e1\u10d0\u10d6\u10dd\u10d2\u10d0\u10d3\u10dd\u10d4\u10d1\u10d0","link":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%90%e1%83%96%e1%83%9d%e1%83%92%e1%83%90%e1%83%93%e1%83%9d%e1%83%94%e1%83%91%e1%83%90\/"},{"label":"\u10e1\u10e3\u10ee\u10d8\u10e8\u10d5\u10d8\u10da\u10d4\u10d1\u10d8\u10e1 \u10e2\u10e0\u10d8\u10e3\u10db\u10e4\u10d8 \u10d9\u10d0\u10e0\u10dc\u10d4\u10d2\u10d8 \u10f0\u10dd\u10da\u10d8\u10e1 \u10e1\u10ea\u10d4\u10dc\u10d0\u10d6\u10d4 | \u10db\u10d7\u10d0\u10d5\u10d0\u10e0\u10d8 \u10e1\u10de\u10dd\u10dc\u10e1\u10dd\u10e0\u10d8 &#8211; \u10e1\u10d0\u10e5\u10d0\u10e0\u10d7\u10d5\u10d4\u10da\u10dd\u10e1 \u10d1\u10d0\u10dc\u10d8","link":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a1%e1%83%a3%e1%83%ae%e1%83%98%e1%83%a8%e1%83%95%e1%83%98%e1%83%9a%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a2%e1%83%a0%e1%83%98%e1%83%a3%e1%83%9b%e1%83%a4%e1%83%98-%e1%83%99%e1%83%90%e1%83%a0\/"}],"_links":{"self":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/73105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/comments?post=73105"}],"version-history":[{"count":1,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/73105\/revisions"}],"predecessor-version":[{"id":73107,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/73105\/revisions\/73107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/media\/73106"}],"wp:attachment":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/media?parent=73105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/categories?post=73105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/tags?post=73105"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/tmauthors?post=73105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}