{"id":39200,"date":"2024-07-08T17:02:50","date_gmt":"2024-07-08T13:02:50","guid":{"rendered":"https:\/\/sheniekimi.ge\/ambebi\/?p=39200"},"modified":"2024-07-08T17:02:50","modified_gmt":"2024-07-08T13:02:50","slug":"%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b","status":"publish","type":"post","link":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/","title":{"rendered":"\u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0"},"content":{"rendered":"<p>1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0.<\/p>\n<p>\u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc &#8211; \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c \u10d3\u10d0 \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10dc\u10d8\u10e3\u10e1\u10d8\u10e1\u201c \u10d2\u10d0\u10d3\u10d0\u10ea\u10d4\u10db\u10d0\u10e8\u10d8 \u201e\u10e1\u10d0\u10e5\u10db\u10d4\u201c \u10d8\u10e1\u10d0\u10e3\u10d1\u10e0\u10d0.<\/p>\n<p>\u201e\u10e3\u10d9\u10d0\u10dc\u10d0\u10e1\u10d9\u10dc\u10d4\u10da\u10d8 \u10e7\u10d5\u10d4\u10da\u10d0\u10d6\u10d4 \u10db\u10ee\u10e1\u10d5\u10d8\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d0, \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d8\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0, \u10d4\u10d5\u10e0\u10dd\u10d3\u10d8\u10e0\u10d4\u10e5\u10e2\u10d8\u10d5\u10d8\u10e1 \u10db\u10dd\u10d7\u10ee\u10dd\u10d5\u10dc\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc \u10d2\u10d0\u10db\u10dd\u10db\u10d3\u10d8\u10dc\u10d0\u10e0\u10d4\u10dd\u10d1\u10e1. \u10e9\u10d0\u10d5\u10d7\u10d5\u10d0\u10da\u10d4\u10d7, \u10e0\u10dd\u10db \u10e1\u10d0\u10ed\u10d8\u10e0\u10dd \u10d8\u10e7\u10dd \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10da\u10d4\u10d1\u10d8\u10e1\u10d7\u10d5\u10d8\u10e1 \u10d0\u10db \u10e3\u10e4\u10da\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10dc\u10d8\u10ed\u10d4\u10d1\u10d0, \u10db\u10d0\u10d7 \u10e8\u10dd\u10e0\u10d8\u10e1 \u10e1\u10d0\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10dd \u10e1\u10d4\u10e5\u10e2\u10dd\u10e0\u10e8\u10d8. 1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10d3\u10d0\u10d6\u10e3\u10e1\u10e2\u10d3\u10d0 \u10d3\u10d0 \u10d2\u10d0\u10d8\u10ec\u10d4\u10e0\u10d0, \u10e0\u10d0 \u10e2\u10d8\u10de\u10d8\u10e1 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d4\u10d1\u10d6\u10d4 \u10e8\u10d4\u10e3\u10eb\u10da\u10d8\u10d0 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0.<\/p>\n<div class=\"ad-component\" data-position=\"inside_article\">\n<div class=\"ad\"><\/div>\n<\/div>\n<p>\u10e7\u10d5\u10d4\u10da\u10d0\u10d6\u10d4 \u10db\u10dc\u10d8\u10e8\u10d5\u10dc\u10d4\u10da\u10dd\u10d5\u10d0\u10dc\u10d8\u10d0 \u10d8\u10e1, \u10e0\u10dd\u10db \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e8\u10d4\u10e3\u10eb\u10da\u10d8\u10d0 \u10dc\u10d4\u10d1\u10d8\u10e1\u10db\u10d8\u10d4\u10e0 \u10d3\u10e0\u10dd\u10e1 \u10d2\u10d0\u10d0\u10e3\u10e5\u10db\u10dd\u10e1 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0, \u10e7\u10dd\u10d5\u10d4\u10da\u10d2\u10d5\u10d0\u10e0\u10d8 \u10db\u10d8\u10d6\u10d4\u10d6\u10d8\u10e1 \u10d2\u10d0\u10e0\u10d4\u10e8\u10d4. \u10d0\u10db\u10d8\u10e1\u10d7\u10d5\u10d8\u10e1 \u10e1\u10d0\u10ed\u10d8\u10e0\u10dd\u10d0 \u10e1\u10de\u10d4\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10e8\u10d4\u10e2\u10e7\u10dd\u10d1\u10d8\u10dc\u10d4\u10d1\u10d0 \u10d2\u10d0\u10e3\u10d2\u10d6\u10d0\u10d5\u10dc\u10dd\u10e1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d4\u10d1\u10e3\u10da\u10d4\u10d1\u10d0\u10e1. \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d5\u10d0\u10d3\u10d0\u10e8\u10d8 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d8 \u10d0\u10d2\u10d6\u10d0\u10d5\u10dc\u10d8\u10e1 \u10e8\u10d4\u10e2\u10e7\u10dd\u10d1\u10d8\u10dc\u10d4\u10d1\u10d0\u10e1 \u10d3\u10d0 30 \u10d3\u10e6\u10d4 \u10d0\u10e5\u10d5\u10e1 \u10db\u10dd\u10db\u10ee\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \/\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d0\u10e1, \u10e0\u10dd\u10db \u10d7\u10d0\u10dc\u10ee\u10d4\u10d1\u10d8, \u10e0\u10dd\u10db\u10da\u10d4\u10d1\u10d8\u10ea \u10d0\u10d8\u10e6\u10d4\u10e1 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1\u10d7\u10d5\u10d8\u10e1, \u10e3\u10d9\u10d0\u10dc \u10d3\u10d0\u10d0\u10d1\u10e0\u10e3\u10dc\u10dd\u10dc.<\/p>\n<p>\u10d0\u10e5 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10da\u10d8\u10e1\u10d7\u10d5\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10eb\u10da\u10dd\u10d0, \u10d2\u10d0\u10e0\u10d9\u10d5\u10d4\u10e3\u10da\u10d8 \u10ee\u10d0\u10e0\u10ef\u10d8\u10ea \u10d3\u10d0\u10d4\u10d9\u10d8\u10e1\u10e0\u10dd\u10e1: \u10db\u10d0\u10d2\u10d0\u10da\u10d8\u10d7\u10d0\u10d3, \u10d7\u10e3 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d8 \u10d2\u10d0\u10d0\u10e3\u10e5\u10db\u10d4\u10d1\u10e1 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10e1, 30 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8 \u10db\u10d0\u10dc \u10e3\u10dc\u10d3\u10d0 \u10db\u10dd\u10d8\u10e2\u10d0\u10dc\u10dd\u10e1 \u10dc\u10d0\u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d8 \u10d7\u10d0\u10dc\u10ee\u10d0 \u10d3\u10d0 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc \u10d7\u10d0\u10dc\u10ee\u10d8\u10e1 \u10d3\u10d0\u10d1\u10e0\u10e3\u10dc\u10d4\u10d1\u10d0\u10db\u10d3\u10d4 \u10de\u10e0\u10dd\u10ea\u10d4\u10dc\u10e2\u10d8. \u10db\u10d0\u10e1 \u10d0\u10e0 \u10db\u10dd\u10e3\u10ec\u10d4\u10d5\u10e1 \u10d2\u10d0\u10ea\u10d4\u10db\u10d8\u10e1 \u10e1\u10d0\u10d9\u10dd\u10db\u10d8\u10e1\u10d8\u10dd\u10e1 \u10d2\u10d0\u10d3\u10d0\u10ee\u10d3\u10d0,\u201c &#8211; \u10d2\u10d0\u10dc\u10d0\u10ea\u10ee\u10d0\u10d3\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0.<\/p>\n<p>\u10db\u10d0\u10dc \u10d0\u10e1\u10d4\u10d5\u10d4 \u10d3\u10d0\u10d0\u10d9\u10dd\u10dc\u10d9\u10e0\u10d4\u10e2\u10d0, \u10e0\u10dd\u10db \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d0 \u10e8\u10d4\u10d4\u10ee\u10d4\u10d1\u10d0 \u10d8\u10e1\u10d4\u10d7 \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10e1, \u10e0\u10dd\u10db\u10da\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10d3\u10d0\u10ec\u10e7\u10d5\u10d4\u10e2\u10d8\u10da\u10d4\u10d1\u10d0\u10e1\u10d0\u10ea \u10d0\u10d3\u10d0\u10db\u10d8\u10d0\u10dc\u10d8 \u10e8\u10d4\u10d3\u10d0\u10e0\u10d4\u10d1\u10d8\u10d7 \u10e1\u10ec\u10e0\u10d0\u10e4\u10d0\u10d3 \u10d8\u10e6\u10d4\u10d1\u10e1, \u10d0\u10dc\u10e3 \u10e1\u10d0\u10da\u10dd\u10db\u10d1\u10d0\u10e0\u10d3\u10d4, \u10d0\u10d5\u10e2\u10dd\u10db\u10dd\u10d1\u10d8\u10da\u10d8\u10d7 \u10e3\u10d6\u10e0\u10e3\u10dc\u10d5\u10d4\u10da\u10e7\u10dd\u10e4\u10d8\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4 \u10d3\u10d0 \u10d8\u10e8\u10d5\u10d8\u10d0\u10d7 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8, \u10d8\u10de\u10dd\u10d7\u10d4\u10d9\u10e3\u10e0 \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4.<\/p>\n<p>\u10d9\u10d8\u10d7\u10ee\u10d5\u10d0\u10d6\u10d4, \u10e8\u10d4\u10d0\u10db\u10ea\u10d8\u10e0\u10d4\u10d1\u10e1 \u10d7\u10e3 \u10d0\u10e0\u10d0 \u10e1\u10d0\u10e9\u10d8\u10d5\u10e0\u10d4\u10d1\u10e1 \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8, \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e3\u10de\u10d0\u10e1\u10e3\u10ee\u10d0, \u10e0\u10dd\u10db \u10d6\u10dd\u10d2\u10d0\u10d3\u10d0\u10d3 \u10e1\u10d0\u10e9\u10d8\u10d5\u10e0\u10d4\u10d1\u10d8\u10e1 \u10e0\u10d0\u10dd\u10d3\u10d4\u10dc\u10dd\u10d1\u10d8\u10e1 \u10d6\u10e0\u10d3\u10d0 \u10e2\u10d4\u10dc\u10d3\u10d4\u10dc\u10ea\u10d8\u10e3\u10e0\u10d8\u10d0 \u10d3\u10d0 \u10d4\u10e1 \u10d0\u10e0 \u10dc\u10d8\u10e8\u10dc\u10d0\u10d5\u10e1, \u10e0\u10dd\u10db \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10d3\u10d0\u10ec\u10d4\u10e1\u10d4\u10d1\u10e3\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10e0\u10d0\u10db\u10d4\u10e1 \u10d0\u10e0\u10d0\u10e1\u10dd\u10e0\u10d0\u10d3 \u10d0\u10d9\u10d4\u10d7\u10d4\u10d1\u10d4\u10dc.<\/p>\n<p>\u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10d8\u10dc\u10e1\u10e2\u10d8\u10e2\u10e3\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10db\u10d0\u10e0\u10d7 \u10de\u10e0\u10d4\u10e2\u10d4\u10dc\u10d6\u10d8\u10d4\u10d1\u10d8\u10e1 \u10d6\u10e0\u10d3\u10d0 \u10dc\u10d8\u10e8\u10dc\u10d0\u10d5\u10e1, \u10e0\u10dd\u10db \u10ea\u10dc\u10dd\u10d1\u10d8\u10d4\u10e0\u10d4\u10d1\u10d0 \u10d2\u10d0\u10d8\u10d6\u10d0\u10e0\u10d3\u10d0 \u10d3\u10d0 \u10d0\u10d3\u10d0\u10db\u10d8\u10d0\u10dc\u10d4\u10d1\u10db\u10d0 \u10e1\u10d0\u10d9\u10e3\u10d7\u10d0\u10e0\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d0 \u10d8\u10e1\u10ec\u10d0\u10d5\u10da\u10d4\u10e1. \u10d0\u10db\u10d8\u10e2\u10dd\u10db \u10e8\u10d4\u10e1\u10d0\u10eb\u10da\u10dd\u10d0, \u10de\u10e0\u10d4\u10e2\u10d4\u10dc\u10d6\u10d8\u10d4\u10d1\u10d8\u10e1 \u10e0\u10d0\u10dd\u10d3\u10d4\u10dc\u10dd\u10d1\u10d0\u10db \u10d9\u10d8\u10d3\u10d4\u10d5 \u10e3\u10e4\u10e0\u10dd \u10db\u10dd\u10d8\u10db\u10d0\u10e2\u10dd\u10e1. \u10d0\u10db\u10d0\u10e1\u10d7\u10d0\u10dc, \u10e1\u10d0\u10e9\u10d8\u10d5\u10e0\u10d4\u10d1\u10d8\u10e1 20%, \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10da\u10d4\u10d1\u10d8\u10e1 \u10e1\u10d0\u10e1\u10d0\u10e0\u10d2\u10d4\u10d1\u10da\u10dd\u10d3 \u10d2\u10d0\u10d3\u10d0\u10ec\u10e7\u10d3\u10d0, \u10d0\u10db\u10d8\u10e2\u10dd\u10db \u10d5\u10d4\u10e0 \u10d5\u10d8\u10e2\u10e7\u10d5\u10d8\u10d7, \u10e0\u10dd\u10db \u10db\u10d0\u10d7 \u10d3\u10d0\u10ec\u10d4\u10e0\u10d0\u10e1 \u10d0\u10d6\u10e0\u10d8 \u10d0\u10e0 \u10d0\u10e5\u10d5\u10e1,\u201c &#8211; \u10d0\u10ea\u10ee\u10d0\u10d3\u10d4\u10d1\u10e1 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10d8.<\/p>\n<p><a href=\"https:\/\/www.bpn.ge\/article\/127030-romeli-sesxis-agebis-shemtxvevashi-shegizliat-xelshekrulebaze-uaris-tkma-da-ra-shemtxvevashi-ara\" target=\"_blank\" rel=\"noopener\"><strong>\u10ec\u10e7\u10d0\u10e0\u10dd<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0. \u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc &#8211; \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[270,274,260,271,264],"tags":[844,1138],"tmauthors":[],"class_list":["post-39200","post","type-post","status-publish","format-standard","has-post-thumbnail","category-270","category-274","category-260","category-271","category-264","tag-844","tag-1138"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0. \u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc - \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"SheniAmbebi.ge\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"ka_GE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8 | \u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"SheniAmbebi.ge | \u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0\" \/>\n\t\t<meta property=\"og:description\" content=\"1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0. \u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc - \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-b94e78021c4c35bfaa03332de279c79d.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-b94e78021c4c35bfaa03332de279c79d.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-07-08T13:02:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-07-08T13:02:50+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sheniambebi\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@drpkhakadze\" \/>\n\t\t<meta name=\"twitter:title\" content=\"SheniAmbebi.ge | \u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0\" \/>\n\t\t<meta name=\"twitter:description\" content=\"1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0. \u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc - \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@drpkhakadze\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-b94e78021c4c35bfaa03332de279c79d.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\\\/#listItem\",\"name\":\"\\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d7\\u10d4\\u10db\\u10d4\\u10d1\\u10d8\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\\\/#listItem\",\"position\":2,\"name\":\"\\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d7\\u10d4\\u10db\\u10d4\\u10d1\\u10d8\",\"item\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\\\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\\\/#listItem\",\"name\":\"\\u10d1\\u10d8\\u10d6\\u10dc\\u10d4\\u10e1\\u10d8\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\\\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\\\/#listItem\",\"position\":3,\"name\":\"\\u10d1\\u10d8\\u10d6\\u10dc\\u10d4\\u10e1\\u10d8\",\"item\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\\\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#listItem\",\"name\":\"\\u10e0\\u10dd\\u10db\\u10d4\\u10da\\u10d8 \\u10e1\\u10d4\\u10e1\\u10ee\\u10d8\\u10e1 \\u10d0\\u10e6\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10e8\\u10d4\\u10d2\\u10d8\\u10eb\\u10da\\u10d8\\u10d0\\u10d7 \\u10ee\\u10d4\\u10da\\u10e8\\u10d4\\u10d9\\u10e0\\u10e3\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e3\\u10d0\\u10e0\\u10d8\\u10e1 \\u10d7\\u10e5\\u10db\\u10d0 \\u10d3\\u10d0 \\u10e0\\u10d0 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10d0\\u10e0\\u10d0\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\\\/#listItem\",\"name\":\"\\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d7\\u10d4\\u10db\\u10d4\\u10d1\\u10d8\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#listItem\",\"position\":4,\"name\":\"\\u10e0\\u10dd\\u10db\\u10d4\\u10da\\u10d8 \\u10e1\\u10d4\\u10e1\\u10ee\\u10d8\\u10e1 \\u10d0\\u10e6\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10e8\\u10d4\\u10d2\\u10d8\\u10eb\\u10da\\u10d8\\u10d0\\u10d7 \\u10ee\\u10d4\\u10da\\u10e8\\u10d4\\u10d9\\u10e0\\u10e3\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e3\\u10d0\\u10e0\\u10d8\\u10e1 \\u10d7\\u10e5\\u10db\\u10d0 \\u10d3\\u10d0 \\u10e0\\u10d0 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10d0\\u10e0\\u10d0\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/category\\\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\\\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\\\/#listItem\",\"name\":\"\\u10d1\\u10d8\\u10d6\\u10dc\\u10d4\\u10e1\\u10d8\"}}]},{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#newsarticle\",\"name\":\"SheniAmbebi.ge | \\u10e0\\u10dd\\u10db\\u10d4\\u10da\\u10d8 \\u10e1\\u10d4\\u10e1\\u10ee\\u10d8\\u10e1 \\u10d0\\u10e6\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10e8\\u10d4\\u10d2\\u10d8\\u10eb\\u10da\\u10d8\\u10d0\\u10d7 \\u10ee\\u10d4\\u10da\\u10e8\\u10d4\\u10d9\\u10e0\\u10e3\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e3\\u10d0\\u10e0\\u10d8\\u10e1 \\u10d7\\u10e5\\u10db\\u10d0 \\u10d3\\u10d0 \\u10e0\\u10d0 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10d0\\u10e0\\u10d0\",\"headline\":\"\\u10e0\\u10dd\\u10db\\u10d4\\u10da\\u10d8 \\u10e1\\u10d4\\u10e1\\u10ee\\u10d8\\u10e1 \\u10d0\\u10e6\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10e8\\u10d4\\u10d2\\u10d8\\u10eb\\u10da\\u10d8\\u10d0\\u10d7 \\u10ee\\u10d4\\u10da\\u10e8\\u10d4\\u10d9\\u10e0\\u10e3\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e3\\u10d0\\u10e0\\u10d8\\u10e1 \\u10d7\\u10e5\\u10db\\u10d0 \\u10d3\\u10d0 \\u10e0\\u10d0 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10d0\\u10e0\\u10d0\",\"author\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/39200-b94e78021c4c35bfaa03332de279c79d.jpg\",\"width\":762,\"height\":476,\"caption\":\"\\u10e1\\u10d4\\u10e1\\u10ee\\u10d8\\u10e1 \\u10d0\\u10e6\\u10d4\\u10d1\\u10d0\"},\"datePublished\":\"2024-07-08T17:02:50+04:00\",\"dateModified\":\"2024-07-08T17:02:50+04:00\",\"inLanguage\":\"ka-GE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#webpage\"},\"articleSection\":\"\\u10d1\\u10d8\\u10d6\\u10dc\\u10d4\\u10e1\\u10d8, \\u10d8\\u10e3\\u10e0\\u10d8\\u10e1\\u10e2\\u10d8, \\u10e0\\u10e9\\u10d4\\u10d5\\u10d4\\u10d1\\u10d8, \\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d3\\u10d0\\u10ee\\u10db\\u10d0\\u10e0\\u10d4\\u10d1\\u10d0, \\u10e1\\u10dd\\u10ea\\u10d8\\u10d0\\u10da\\u10e3\\u10e0\\u10d8 \\u10d7\\u10d4\\u10db\\u10d4\\u10d1\\u10d8, \\u10e1\\u10d0\\u10de\\u10d4\\u10dc\\u10e1\\u10d8\\u10dd \\u10e1\\u10d4\\u10e1\\u10ee\\u10d8, \\u10e1\\u10d4\\u10e1\\u10ee\\u10d8\",\"dateline\":\"Published on \\u10d8\\u10d5\\u10da\\u10d8\\u10e1\\u10d8 8, 2024.\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\",\"name\":\"Sheniambebi\",\"description\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/\",\"telephone\":\"+995577416314\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/39200-8ad006f7e722452ea3f782fb503e5d96.jpg\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#organizationLogo\",\"width\":793,\"height\":228},\"image\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sheniambebi\",\"https:\\\/\\\/x.com\\\/drpkhakadze\",\"https:\\\/\\\/www.instagram.com\\\/sheniambebi.ge\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@shenipulsi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/\",\"name\":\"SheniAmbebi.ge\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#webpage\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/\",\"name\":\"SheniAmbebi.ge | \\u10e0\\u10dd\\u10db\\u10d4\\u10da\\u10d8 \\u10e1\\u10d4\\u10e1\\u10ee\\u10d8\\u10e1 \\u10d0\\u10e6\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10e8\\u10d4\\u10d2\\u10d8\\u10eb\\u10da\\u10d8\\u10d0\\u10d7 \\u10ee\\u10d4\\u10da\\u10e8\\u10d4\\u10d9\\u10e0\\u10e3\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4 \\u10e3\\u10d0\\u10e0\\u10d8\\u10e1 \\u10d7\\u10e5\\u10db\\u10d0 \\u10d3\\u10d0 \\u10e0\\u10d0 \\u10e8\\u10d4\\u10db\\u10d7\\u10ee\\u10d5\\u10d4\\u10d5\\u10d0\\u10e8\\u10d8 \\u10d0\\u10e0\\u10d0\",\"description\":\"1-\\u10da\\u10d8 \\u10d8\\u10d5\\u10da\\u10d8\\u10e1\\u10d8\\u10d3\\u10d0\\u10dc \\u10db\\u10dd\\u10db\\u10ee\\u10db\\u10d0\\u10e0\\u10d4\\u10d1\\u10d4\\u10da\\u10e1 \\u10e3\\u10e4\\u10da\\u10d4\\u10d1\\u10d0 \\u10d0\\u10e5\\u10d5\\u10e1 \\u10e3\\u10d0\\u10e0\\u10d8 \\u10d7\\u10e5\\u10d5\\u10d0\\u10e1 \\u10d3\\u10d8\\u10e1\\u10e2\\u10d0\\u10dc\\u10ea\\u10d8\\u10e3\\u10e0\\u10d0\\u10d3 \\u10d3\\u10d0\\u10d3\\u10d4\\u10d1\\u10e3\\u10da \\u10ee\\u10d4\\u10da\\u10e8\\u10d4\\u10d9\\u10e0\\u10e3\\u10da\\u10d4\\u10d1\\u10d0\\u10d6\\u10d4, \\u10d0\\u10e1\\u10d4\\u10d5\\u10d4, \\u10d4\\u10e0\\u10d7 \\u10db\\u10d8\\u10da\\u10d8\\u10dd\\u10dc \\u10da\\u10d0\\u10e0\\u10d0\\u10db\\u10d3\\u10d4 \\u10d2\\u10d0\\u10ea\\u10d4\\u10db\\u10e3\\u10da \\u10e1\\u10d4\\u10e1\\u10ee\\u10d4\\u10d1\\u10d6\\u10d4\\\/\\u10d9\\u10e0\\u10d4\\u10d3\\u10d8\\u10e2\\u10d4\\u10d1\\u10d6\\u10d4 \\u10db\\u10d0\\u10d7\\u10d8 \\u10d2\\u10d0\\u10e4\\u10dd\\u10e0\\u10db\\u10d4\\u10d1\\u10d8\\u10d3\\u10d0\\u10dc 14 \\u10d3\\u10e6\\u10d8\\u10e1 \\u10d2\\u10d0\\u10dc\\u10db\\u10d0\\u10d5\\u10da\\u10dd\\u10d1\\u10d0\\u10e8\\u10d8. \\u10d0\\u10e6\\u10dc\\u10d8\\u10e8\\u10dc\\u10e3\\u10da\\u10d8 \\u10ea\\u10d5\\u10da\\u10d8\\u10da\\u10d4\\u10d1\\u10d4\\u10d1\\u10d8 \\u10eb\\u10d0\\u10da\\u10d0\\u10e8\\u10d8 \\u201e\\u10e4\\u10d8\\u10dc\\u10d0\\u10dc\\u10e1\\u10e3\\u10e0\\u10d8 \\u10dd\\u10e0\\u10d2\\u10d0\\u10dc\\u10d8\\u10d6\\u10d0\\u10ea\\u10d8\\u10d4\\u10d1\\u10d8\\u10e1 \\u10db\\u10d8\\u10d4\\u10e0 \\u10db\\u10dd\\u10db\\u10e1\\u10d0\\u10ee\\u10e3\\u10e0\\u10d4\\u10d1\\u10d8\\u10e1 \\u10d2\\u10d0\\u10ec\\u10d4\\u10d5\\u10d8\\u10e1\\u10d0\\u10e1 \\u10db\\u10dd\\u10db\\u10ee\\u10db\\u10d0\\u10e0\\u10d4\\u10d1\\u10d4\\u10da\\u10d7\\u10d0 \\u10e3\\u10e4\\u10da\\u10d4\\u10d1\\u10d4\\u10d1\\u10d8\\u10e1 \\u10d3\\u10d0\\u10ea\\u10d5\\u10d8\\u10e1 \\u10ec\\u10d4\\u10e1\\u10e8\\u10d8\\u201c \\u10e8\\u10d4\\u10d5\\u10d8\\u10d3\\u10d0. \\u10e0\\u10d0 \\u10e3\\u10dc\\u10d3\\u10d0 \\u10d5\\u10d8\\u10ea\\u10dd\\u10d3\\u10d4\\u10d7 \\u10e9\\u10d5\\u10d4\\u10dc\\u10d8 \\u10e3\\u10e4\\u10da\\u10d4\\u10d1\\u10d4\\u10d1\\u10d8\\u10e1 \\u10e8\\u10d4\\u10e1\\u10d0\\u10ee\\u10d4\\u10d1 \\u10e4\\u10d8\\u10dc\\u10d0\\u10dc\\u10e1\\u10e3\\u10e0 \\u10dd\\u10e0\\u10d2\\u10d0\\u10dc\\u10d8\\u10d6\\u10d0\\u10ea\\u10d8\\u10d4\\u10d1\\u10d7\\u10d0\\u10dc - \\u10d0\\u10db\\u10d8\\u10e1 \\u10e8\\u10d4\\u10e1\\u10d0\\u10ee\\u10d4\\u10d1 \\u10e1\\u10d4\\u10d1-\\u10d8\\u10e1 \\u10db\\u10dd\\u10db\\u10ee\\u10db\\u10d0\\u10e0\\u10d4\\u10d1\\u10d4\\u10da\\u10d7\\u10d0 \\u10e3\\u10e4\\u10da\\u10d4\\u10d1\\u10d4\\u10d1\\u10d8\\u10e1 \\u10d3\\u10d0\\u10ea\\u10d5\\u10d8\\u10e1 \\u10d3\\u10d4\\u10de\\u10d0\\u10e0\\u10e2\\u10d0\\u10db\\u10d4\\u10dc\\u10e2\\u10d8\\u10e1 \\u10e3\\u10e4\\u10e0\\u10dd\\u10e1\\u10db\\u10d0 \\u10da\\u10d0\\u10e8\\u10d0 \\u10d2\\u10d6\\u10d8\\u10e0\\u10d8\\u10e8\\u10d5\\u10d8\\u10da\\u10db\\u10d0 \\u10e0\\u10d0\\u10d3\\u10d8\\u10dd \\u201e\\u10de\\u10d0\\u10da\\u10d8\\u10e2\\u10e0\\u10d0\\u10e1\\u10d0\\u201c\",\"inLanguage\":\"ka-GE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/author\\\/giorgi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/wp-content\\\/uploads\\\/sf-branded\\\/39200-b94e78021c4c35bfaa03332de279c79d.jpg\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#mainImage\",\"width\":762,\"height\":476,\"caption\":\"\\u10e1\\u10d4\\u10e1\\u10ee\\u10d8\\u10e1 \\u10d0\\u10e6\\u10d4\\u10d1\\u10d0\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\\\/#mainImage\"},\"datePublished\":\"2024-07-08T17:02:50+04:00\",\"dateModified\":\"2024-07-08T17:02:50+04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#website\",\"url\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/\",\"name\":\"SheniAmbebi\",\"alternateName\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"description\":\"\\u10e8\\u10d4\\u10dc\\u10d8 \\u10d0\\u10db\\u10d1\\u10d4\\u10d1\\u10d8\",\"inLanguage\":\"ka-GE\",\"publisher\":{\"@id\":\"https:\\\/\\\/sheniekimi.ge\\\/ambebi\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>SheniAmbebi.ge | \u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0<\/title>\n\n","aioseo_head_json":{"title":"SheniAmbebi.ge | \u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0","description":"1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0. \u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc - \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c","canonical_url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi#listItem","position":1,"name":"Home","item":"https:\/\/sheniekimi.ge\/ambebi","nextItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/#listItem","name":"\u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d7\u10d4\u10db\u10d4\u10d1\u10d8"}},{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/#listItem","position":2,"name":"\u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d7\u10d4\u10db\u10d4\u10d1\u10d8","item":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\/#listItem","name":"\u10d1\u10d8\u10d6\u10dc\u10d4\u10e1\u10d8"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\/#listItem","position":3,"name":"\u10d1\u10d8\u10d6\u10dc\u10d4\u10e1\u10d8","item":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#listItem","name":"\u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/#listItem","name":"\u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d7\u10d4\u10db\u10d4\u10d1\u10d8"}},{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#listItem","position":4,"name":"\u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0","previousItem":{"@type":"ListItem","@id":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\/#listItem","name":"\u10d1\u10d8\u10d6\u10dc\u10d4\u10e1\u10d8"}}]},{"@type":"NewsArticle","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#newsarticle","name":"SheniAmbebi.ge | \u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0","headline":"\u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0","author":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"publisher":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-b94e78021c4c35bfaa03332de279c79d.jpg","width":762,"height":476,"caption":"\u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d0"},"datePublished":"2024-07-08T17:02:50+04:00","dateModified":"2024-07-08T17:02:50+04:00","inLanguage":"ka-GE","mainEntityOfPage":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#webpage"},"isPartOf":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#webpage"},"articleSection":"\u10d1\u10d8\u10d6\u10dc\u10d4\u10e1\u10d8, \u10d8\u10e3\u10e0\u10d8\u10e1\u10e2\u10d8, \u10e0\u10e9\u10d4\u10d5\u10d4\u10d1\u10d8, \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d3\u10d0\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d0, \u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d7\u10d4\u10db\u10d4\u10d1\u10d8, \u10e1\u10d0\u10de\u10d4\u10dc\u10e1\u10d8\u10dd \u10e1\u10d4\u10e1\u10ee\u10d8, \u10e1\u10d4\u10e1\u10ee\u10d8","dateline":"Published on \u10d8\u10d5\u10da\u10d8\u10e1\u10d8 8, 2024."},{"@type":"Organization","@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization","name":"Sheniambebi","description":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","url":"https:\/\/sheniekimi.ge\/ambebi\/","telephone":"+995577416314","logo":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-8ad006f7e722452ea3f782fb503e5d96.jpg","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#organizationLogo","width":793,"height":228},"image":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/sheniambebi","https:\/\/x.com\/drpkhakadze","https:\/\/www.instagram.com\/sheniambebi.ge\/","https:\/\/www.tiktok.com\/@shenipulsi"]},{"@type":"Person","@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author","url":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/","name":"SheniAmbebi.ge"},{"@type":"WebPage","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#webpage","url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/","name":"SheniAmbebi.ge | \u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0","description":"1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0. \u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc - \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c","inLanguage":"ka-GE","isPartOf":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#website"},"breadcrumb":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#breadcrumblist"},"author":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"creator":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/author\/giorgi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-b94e78021c4c35bfaa03332de279c79d.jpg","@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#mainImage","width":762,"height":476,"caption":"\u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d0"},"primaryImageOfPage":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/#mainImage"},"datePublished":"2024-07-08T17:02:50+04:00","dateModified":"2024-07-08T17:02:50+04:00"},{"@type":"WebSite","@id":"https:\/\/sheniekimi.ge\/ambebi\/#website","url":"https:\/\/sheniekimi.ge\/ambebi\/","name":"SheniAmbebi","alternateName":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","description":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","inLanguage":"ka-GE","publisher":{"@id":"https:\/\/sheniekimi.ge\/ambebi\/#organization"}}]},"og:locale":"ka_GE","og:site_name":"\u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8 | \u10e8\u10d4\u10dc\u10d8 \u10d0\u10db\u10d1\u10d4\u10d1\u10d8","og:type":"article","og:title":"SheniAmbebi.ge | \u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0","og:description":"1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0. \u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc - \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c","og:url":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/","og:image":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-b94e78021c4c35bfaa03332de279c79d.jpg","og:image:secure_url":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-b94e78021c4c35bfaa03332de279c79d.jpg","og:image:width":762,"og:image:height":476,"article:published_time":"2024-07-08T13:02:50+00:00","article:modified_time":"2024-07-08T13:02:50+00:00","article:publisher":"https:\/\/www.facebook.com\/sheniambebi","twitter:card":"summary_large_image","twitter:site":"@drpkhakadze","twitter:title":"SheniAmbebi.ge | \u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0","twitter:description":"1-\u10da\u10d8 \u10d8\u10d5\u10da\u10d8\u10e1\u10d8\u10d3\u10d0\u10dc \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10e1 \u10e3\u10e4\u10da\u10d4\u10d1\u10d0 \u10d0\u10e5\u10d5\u10e1 \u10e3\u10d0\u10e0\u10d8 \u10d7\u10e5\u10d5\u10d0\u10e1 \u10d3\u10d8\u10e1\u10e2\u10d0\u10dc\u10ea\u10d8\u10e3\u10e0\u10d0\u10d3 \u10d3\u10d0\u10d3\u10d4\u10d1\u10e3\u10da \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4, \u10d0\u10e1\u10d4\u10d5\u10d4, \u10d4\u10e0\u10d7 \u10db\u10d8\u10da\u10d8\u10dd\u10dc \u10da\u10d0\u10e0\u10d0\u10db\u10d3\u10d4 \u10d2\u10d0\u10ea\u10d4\u10db\u10e3\u10da \u10e1\u10d4\u10e1\u10ee\u10d4\u10d1\u10d6\u10d4\/\u10d9\u10e0\u10d4\u10d3\u10d8\u10e2\u10d4\u10d1\u10d6\u10d4 \u10db\u10d0\u10d7\u10d8 \u10d2\u10d0\u10e4\u10dd\u10e0\u10db\u10d4\u10d1\u10d8\u10d3\u10d0\u10dc 14 \u10d3\u10e6\u10d8\u10e1 \u10d2\u10d0\u10dc\u10db\u10d0\u10d5\u10da\u10dd\u10d1\u10d0\u10e8\u10d8. \u10d0\u10e6\u10dc\u10d8\u10e8\u10dc\u10e3\u10da\u10d8 \u10ea\u10d5\u10da\u10d8\u10da\u10d4\u10d1\u10d4\u10d1\u10d8 \u10eb\u10d0\u10da\u10d0\u10e8\u10d8 \u201e\u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0\u10d8 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d8\u10e1 \u10db\u10d8\u10d4\u10e0 \u10db\u10dd\u10db\u10e1\u10d0\u10ee\u10e3\u10e0\u10d4\u10d1\u10d8\u10e1 \u10d2\u10d0\u10ec\u10d4\u10d5\u10d8\u10e1\u10d0\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10ec\u10d4\u10e1\u10e8\u10d8\u201c \u10e8\u10d4\u10d5\u10d8\u10d3\u10d0. \u10e0\u10d0 \u10e3\u10dc\u10d3\u10d0 \u10d5\u10d8\u10ea\u10dd\u10d3\u10d4\u10d7 \u10e9\u10d5\u10d4\u10dc\u10d8 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e4\u10d8\u10dc\u10d0\u10dc\u10e1\u10e3\u10e0 \u10dd\u10e0\u10d2\u10d0\u10dc\u10d8\u10d6\u10d0\u10ea\u10d8\u10d4\u10d1\u10d7\u10d0\u10dc - \u10d0\u10db\u10d8\u10e1 \u10e8\u10d4\u10e1\u10d0\u10ee\u10d4\u10d1 \u10e1\u10d4\u10d1-\u10d8\u10e1 \u10db\u10dd\u10db\u10ee\u10db\u10d0\u10e0\u10d4\u10d1\u10d4\u10da\u10d7\u10d0 \u10e3\u10e4\u10da\u10d4\u10d1\u10d4\u10d1\u10d8\u10e1 \u10d3\u10d0\u10ea\u10d5\u10d8\u10e1 \u10d3\u10d4\u10de\u10d0\u10e0\u10e2\u10d0\u10db\u10d4\u10dc\u10e2\u10d8\u10e1 \u10e3\u10e4\u10e0\u10dd\u10e1\u10db\u10d0 \u10da\u10d0\u10e8\u10d0 \u10d2\u10d6\u10d8\u10e0\u10d8\u10e8\u10d5\u10d8\u10da\u10db\u10d0 \u10e0\u10d0\u10d3\u10d8\u10dd \u201e\u10de\u10d0\u10da\u10d8\u10e2\u10e0\u10d0\u10e1\u10d0\u201c","twitter:creator":"@drpkhakadze","twitter:image":"https:\/\/sheniekimi.ge\/ambebi\/wp-content\/uploads\/sf-branded\/39200-b94e78021c4c35bfaa03332de279c79d.jpg"},"aioseo_meta_data":{"post_id":"39200","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"NewsArticle","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-21 02:16:27","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2024-07-08 13:02:50","updated":"2026-05-21 02:16:27","focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sheniekimi.ge\/ambebi\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/\" title=\"\u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d7\u10d4\u10db\u10d4\u10d1\u10d8\">\u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d7\u10d4\u10db\u10d4\u10d1\u10d8<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\/\" title=\"\u10d1\u10d8\u10d6\u10dc\u10d4\u10e1\u10d8\">\u10d1\u10d8\u10d6\u10dc\u10d4\u10e1\u10d8<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/sheniekimi.ge\/ambebi"},{"label":"\u10e1\u10dd\u10ea\u10d8\u10d0\u10da\u10e3\u10e0\u10d8 \u10d7\u10d4\u10db\u10d4\u10d1\u10d8","link":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/"},{"label":"\u10d1\u10d8\u10d6\u10dc\u10d4\u10e1\u10d8","link":"https:\/\/sheniekimi.ge\/ambebi\/category\/%e1%83%a1%e1%83%9d%e1%83%aa%e1%83%98%e1%83%90%e1%83%9a%e1%83%a3%e1%83%a0%e1%83%98-%e1%83%97%e1%83%94%e1%83%9b%e1%83%94%e1%83%91%e1%83%98\/%e1%83%91%e1%83%98%e1%83%96%e1%83%9c%e1%83%94%e1%83%a1%e1%83%98\/"},{"label":"\u10e0\u10dd\u10db\u10d4\u10da\u10d8 \u10e1\u10d4\u10e1\u10ee\u10d8\u10e1 \u10d0\u10e6\u10d4\u10d1\u10d8\u10e1 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10e8\u10d4\u10d2\u10d8\u10eb\u10da\u10d8\u10d0\u10d7 \u10ee\u10d4\u10da\u10e8\u10d4\u10d9\u10e0\u10e3\u10da\u10d4\u10d1\u10d0\u10d6\u10d4 \u10e3\u10d0\u10e0\u10d8\u10e1 \u10d7\u10e5\u10db\u10d0 \u10d3\u10d0 \u10e0\u10d0 \u10e8\u10d4\u10db\u10d7\u10ee\u10d5\u10d4\u10d5\u10d0\u10e8\u10d8 \u10d0\u10e0\u10d0","link":"https:\/\/sheniekimi.ge\/ambebi\/%e1%83%a0%e1%83%9d%e1%83%9b%e1%83%94%e1%83%9a%e1%83%98-%e1%83%a1%e1%83%94%e1%83%a1%e1%83%ae%e1%83%98%e1%83%a1-%e1%83%90%e1%83%a6%e1%83%94%e1%83%91%e1%83%98%e1%83%a1-%e1%83%a8%e1%83%94%e1%83%9b\/"}],"_links":{"self":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/39200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/comments?post=39200"}],"version-history":[{"count":1,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/39200\/revisions"}],"predecessor-version":[{"id":39201,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/posts\/39200\/revisions\/39201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/media\/33886"}],"wp:attachment":[{"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/media?parent=39200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/categories?post=39200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/tags?post=39200"},{"taxonomy":"tmauthors","embeddable":true,"href":"https:\/\/sheniekimi.ge\/ambebi\/wp-json\/wp\/v2\/tmauthors?post=39200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}